{"id":1105,"date":"2012-11-27T10:51:57","date_gmt":"2012-11-27T12:51:57","guid":{"rendered":"http:\/\/www.encontracentrosaopaulo.com.br\/noticias\/?p=1105"},"modified":"2019-04-29T16:21:35","modified_gmt":"2019-04-29T19:21:35","slug":"quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp","status":"publish","type":"post","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\/","title":{"rendered":"Quatro sem-teto s\u00e3o baleados durante ocupa\u00e7\u00e3o no centro de SP"},"content":{"rendered":"<div class=\"d6585b5127f45a35450431d0abc3f90c\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Quatro pessoas foram baleadas em uma tentativa de ocupa\u00e7\u00e3o de pr\u00e9dio no centro da capital paulista, na madrugada da \u00faltima sexta feira (24), de acordo com informa\u00e7\u00f5es da Secretaria de Seguran\u00e7a P\u00fablica (SSP). O caso aconteceu na Rua Riachuelo, esquina com a Avenida 23 de Maio, por volta das 2h30. Ao tentar ocupar o pr\u00e9dio, os sem-teto foram recebidos a tiros.<\/p>\n<p>Policiais militares que atenderam a ocorr\u00eancia informaram que o propriet\u00e1rio do local, um homem de 65 anos, assumiu a autoria dos disparos. Por outro lado, ao serem colhidos os depoimentos de tr\u00eas dos quatro feridos j\u00e1 no hospital, as v\u00edtimas disseram que o autor dos disparos n\u00e3o seria o propriet\u00e1rio do pr\u00e9dio.<\/p>\n<p>O suspeito foi submetido a exame residuogr\u00e1fico para verificar se h\u00e1 vest\u00edgio de p\u00f3lvora. Ele foi detido para averigua\u00e7\u00e3o do fato e, em seguida, liberado.<\/p>\n<p>Segundo o boletim de ocorr\u00eancia, foram tr\u00eas feridos do sexo masculino: um aut\u00f4nomo, com 31 anos; um carteiro, com 43 anos; e um servente, com 22 anos. Uma cozinheira de 57 anos tamb\u00e9m foi atingida. A secretaria informou que tr\u00eas dos feridos foram socorridos no Pronto Socorro Vergueiro e outro foi levado ao Hospital Gl\u00f3ria.<\/p>\n<p><em>Fonte: Correio do Brasil<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Quatro pessoas foram baleadas em uma tentativa de ocupa\u00e7\u00e3o de pr\u00e9dio no centro da capital paulista, na madrugada da \u00faltima sexta feira (24), de acordo com informa\u00e7\u00f5es da Secretaria de Seguran\u00e7a P\u00fablica (SSP). O caso aconteceu na Rua Riachuelo, esquina com a Avenida 23 de Maio, por volta das 2h30. Ao tentar ocupar o pr\u00e9dio, os sem-teto foram recebidos a tiros. Policiais militares que atenderam a ocorr\u00eancia informaram que o propriet\u00e1rio do local, um homem de 65 anos, assumiu a autoria dos disparos. Por outro lado, ao serem colhidos os depoimentos de tr\u00eas dos quatro feridos j\u00e1 no hospital, as <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1105","post","type-post","status-publish","format-standard","hentry","category-noticias-no-centro-sp"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Quatro pessoas foram baleadas em uma tentativa de ocupa\u00e7\u00e3o de pr\u00e9dio no centro da capital paulista, na madrugada da \u00faltima sexta feira (24), de acordo com informa\u00e7\u00f5es da Secretaria de Seguran\u00e7a P\u00fablica (SSP). O caso aconteceu na Rua Riachuelo, esquina com a Avenida 23 de Maio, por volta das 2h30. Ao tentar ocupar o pr\u00e9dio,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Encontra Centro SP\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Encontra Centro SP | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Quatro sem-teto s\u00e3o baleados durante ocupa\u00e7\u00e3o no centro de SP | Encontra Centro SP\" \/>\n\t\t<meta property=\"og:description\" content=\"Quatro pessoas foram baleadas em uma tentativa de ocupa\u00e7\u00e3o de pr\u00e9dio no centro da capital paulista, na madrugada da \u00faltima sexta feira (24), de acordo com informa\u00e7\u00f5es da Secretaria de Seguran\u00e7a P\u00fablica (SSP). O caso aconteceu na Rua Riachuelo, esquina com a Avenida 23 de Maio, por volta das 2h30. Ao tentar ocupar o pr\u00e9dio,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-11-27T12:51:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-29T19:21:35+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Quatro sem-teto s\u00e3o baleados durante ocupa\u00e7\u00e3o no centro de SP | Encontra Centro SP\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Quatro pessoas foram baleadas em uma tentativa de ocupa\u00e7\u00e3o de pr\u00e9dio no centro da capital paulista, na madrugada da \u00faltima sexta feira (24), de acordo com informa\u00e7\u00f5es da Secretaria de Seguran\u00e7a P\u00fablica (SSP). O caso aconteceu na Rua Riachuelo, esquina com a Avenida 23 de Maio, por volta das 2h30. Ao tentar ocupar o pr\u00e9dio,\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\\\/#article\",\"name\":\"Quatro sem-teto s\\u00e3o baleados durante ocupa\\u00e7\\u00e3o no centro de SP | Encontra Centro SP\",\"headline\":\"Quatro sem-teto s\\u00e3o baleados durante ocupa\\u00e7\\u00e3o no centro de SP\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\"},\"datePublished\":\"2012-11-27T10:51:57-02:00\",\"dateModified\":\"2019-04-29T16:21:35-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias Centro SP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"name\":\"Not\\u00edcias Centro SP\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias Centro SP\",\"item\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\\\/#listItem\",\"name\":\"Quatro sem-teto s\\u00e3o baleados durante ocupa\\u00e7\\u00e3o no centro de SP\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\\\/#listItem\",\"position\":3,\"name\":\"Quatro sem-teto s\\u00e3o baleados durante ocupa\\u00e7\\u00e3o no centro de SP\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"name\":\"Not\\u00edcias Centro SP\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\",\"name\":\"Encontra Centro SP\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Centro SP e regi\\u00e3o.\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/\",\"name\":\"Encontra Centro SP\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Encontra Centro SP\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\\\/#webpage\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\\\/\",\"name\":\"Quatro sem-teto s\\u00e3o baleados durante ocupa\\u00e7\\u00e3o no centro de SP | Encontra Centro SP\",\"description\":\"Quatro pessoas foram baleadas em uma tentativa de ocupa\\u00e7\\u00e3o de pr\\u00e9dio no centro da capital paulista, na madrugada da \\u00faltima sexta feira (24), de acordo com informa\\u00e7\\u00f5es da Secretaria de Seguran\\u00e7a P\\u00fablica (SSP). O caso aconteceu na Rua Riachuelo, esquina com a Avenida 23 de Maio, por volta das 2h30. Ao tentar ocupar o pr\\u00e9dio,\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"datePublished\":\"2012-11-27T10:51:57-02:00\",\"dateModified\":\"2019-04-29T16:21:35-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/\",\"name\":\"Encontra Centro SP\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Centro SP e regi\\u00e3o.\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Quatro sem-teto s\u00e3o baleados durante ocupa\u00e7\u00e3o no centro de SP | Encontra Centro SP","description":"Quatro pessoas foram baleadas em uma tentativa de ocupa\u00e7\u00e3o de pr\u00e9dio no centro da capital paulista, na madrugada da \u00faltima sexta feira (24), de acordo com informa\u00e7\u00f5es da Secretaria de Seguran\u00e7a P\u00fablica (SSP). O caso aconteceu na Rua Riachuelo, esquina com a Avenida 23 de Maio, por volta das 2h30. Ao tentar ocupar o pr\u00e9dio,","canonical_url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\/#article","name":"Quatro sem-teto s\u00e3o baleados durante ocupa\u00e7\u00e3o no centro de SP | Encontra Centro SP","headline":"Quatro sem-teto s\u00e3o baleados durante ocupa\u00e7\u00e3o no centro de SP","author":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"publisher":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization"},"datePublished":"2012-11-27T10:51:57-02:00","dateModified":"2019-04-29T16:21:35-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\/#webpage"},"isPartOf":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\/#webpage"},"articleSection":"Not\u00edcias Centro SP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","name":"Not\u00edcias Centro SP"}},{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","position":2,"name":"Not\u00edcias Centro SP","item":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\/#listItem","name":"Quatro sem-teto s\u00e3o baleados durante ocupa\u00e7\u00e3o no centro de SP"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\/#listItem","position":3,"name":"Quatro sem-teto s\u00e3o baleados durante ocupa\u00e7\u00e3o no centro de SP","previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","name":"Not\u00edcias Centro SP"}}]},{"@type":"Organization","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization","name":"Encontra Centro SP","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/"},{"@type":"Person","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/","name":"Encontra Centro SP","image":{"@type":"ImageObject","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","width":96,"height":96,"caption":"Encontra Centro SP"}},{"@type":"WebPage","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\/#webpage","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\/","name":"Quatro sem-teto s\u00e3o baleados durante ocupa\u00e7\u00e3o no centro de SP | Encontra Centro SP","description":"Quatro pessoas foram baleadas em uma tentativa de ocupa\u00e7\u00e3o de pr\u00e9dio no centro da capital paulista, na madrugada da \u00faltima sexta feira (24), de acordo com informa\u00e7\u00f5es da Secretaria de Seguran\u00e7a P\u00fablica (SSP). O caso aconteceu na Rua Riachuelo, esquina com a Avenida 23 de Maio, por volta das 2h30. Ao tentar ocupar o pr\u00e9dio,","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#website"},"breadcrumb":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\/#breadcrumblist"},"author":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"creator":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"datePublished":"2012-11-27T10:51:57-02:00","dateModified":"2019-04-29T16:21:35-03:00"},{"@type":"WebSite","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#website","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/","name":"Encontra Centro SP","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Encontra Centro SP | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","og:type":"article","og:title":"Quatro sem-teto s\u00e3o baleados durante ocupa\u00e7\u00e3o no centro de SP | Encontra Centro SP","og:description":"Quatro pessoas foram baleadas em uma tentativa de ocupa\u00e7\u00e3o de pr\u00e9dio no centro da capital paulista, na madrugada da \u00faltima sexta feira (24), de acordo com informa\u00e7\u00f5es da Secretaria de Seguran\u00e7a P\u00fablica (SSP). O caso aconteceu na Rua Riachuelo, esquina com a Avenida 23 de Maio, por volta das 2h30. Ao tentar ocupar o pr\u00e9dio,","og:url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\/","article:published_time":"2012-11-27T12:51:57+00:00","article:modified_time":"2019-04-29T19:21:35+00:00","twitter:card":"summary","twitter:title":"Quatro sem-teto s\u00e3o baleados durante ocupa\u00e7\u00e3o no centro de SP | Encontra Centro SP","twitter:description":"Quatro pessoas foram baleadas em uma tentativa de ocupa\u00e7\u00e3o de pr\u00e9dio no centro da capital paulista, na madrugada da \u00faltima sexta feira (24), de acordo com informa\u00e7\u00f5es da Secretaria de Seguran\u00e7a P\u00fablica (SSP). O caso aconteceu na Rua Riachuelo, esquina com a Avenida 23 de Maio, por volta das 2h30. Ao tentar ocupar o pr\u00e9dio,"},"aioseo_meta_data":{"post_id":"1105","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-18 18:59:39","updated":"2025-11-15 16:57:42","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/\" title=\"Not\u00edcias Centro SP\">Not\u00edcias Centro SP<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tQuatro sem-teto s\u00e3o baleados durante ocupa\u00e7\u00e3o no centro de SP\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre"},{"label":"Not\u00edcias Centro SP","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/"},{"label":"Quatro sem-teto s\u00e3o baleados durante ocupa\u00e7\u00e3o no centro de SP","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/quatro-sem-teto-sao-baleados-durante-ocupacao-no-centro-de-sp\/"}],"_links":{"self":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=1105"}],"version-history":[{"count":0,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1105\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=1105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=1105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=1105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}