{"id":1646,"date":"2013-06-14T15:17:37","date_gmt":"2013-06-14T17:17:37","guid":{"rendered":"http:\/\/www.encontracentrosaopaulo.com.br\/noticias\/?p=1646"},"modified":"2019-04-29T16:20:05","modified_gmt":"2019-04-29T19:20:05","slug":"policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo","status":"publish","type":"post","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\/","title":{"rendered":"Pol\u00edcia Militar utiliza viol\u00eancia para reprimir protesto no Centro de S\u00e3o Paulo"},"content":{"rendered":"<div class=\"d6585b5127f45a35450431d0abc3f90c\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Uma noite de viol\u00eancia e p\u00e2nico na cidade de S\u00e3o Paulo. O quarto dia de protestos contra o aumento da tarifa do transporte p\u00fablico transformou as ruas da maior cidade do pa\u00eds em um cen\u00e1rio de guerra.<\/p>\n<p>Foram seis horas de protesto. Dessa vez, a pol\u00edcia endureceu a repress\u00e3o, agindo com viol\u00eancia. Duzentas pessoas foram detidas e dezenas ficaram feridas. Muita gente que n\u00e3o fazia parte do protesto tamb\u00e9m ficou no meio de tiros e pedras.<\/p>\n<p>No quarto dia de protestos contra o aumento da tarifa de \u00f4nibus, a repress\u00e3o policial foi mais intensa.<\/p>\n<p>Uma noite que terminou com mais de 200 presos, muitos feridos, e popula\u00e7\u00e3o assustada.<\/p>\n<p>N\u00e3o era o que o movimento pedia. Os manifestantes se reuniram em frente ao Teatro Municipal. A pol\u00edcia revistou quem estava de mochila. E j\u00e1 prendeu dezenas de pessoas antes mesmo da passeata.<\/p>\n<p>Quando enfim come\u00e7ou, a marcha seguiu pac\u00edfica. Mas a tranquilidade acabou logo. Apenas meia hora depois, quando os manifestantes tentavam subir uma das principais ruas da cidade.<\/p>\n<p>\u201cA orienta\u00e7\u00e3o \u00e9 a que eles n\u00e3o subam a Rua da Consola\u00e7\u00e3o em dire\u00e7\u00e3o \u00e0 Avenida Paulista. Isso me parece bastante claro, \u00e9 s\u00f3 quest\u00e3o de cumprir acordo, agora se n\u00e3o \u00e9 para cumprir acordo, n\u00e3o reclame do resultado\u201d, declara um policial.<\/p>\n<p>Foi o pren\u00fancio do que viria. Do alto, deu para ver o tamanho da guerra. Os confrontos durariam mais de quatro horas.<\/p>\n<p>Dessa vez, o tumulto acontece no meio de muita gente, no meio da popula\u00e7\u00e3o. A Tropa de Choque disparou bombas de g\u00e1s, bombas de efeito moral, tiro de balas de borracha. Motoristas ficaram parados no tr\u00e2nsito entre os manifestantes. \u201cTodo mundo preso no posto, tivemos que se abrir aqui dentro para fugir dos gases, estava muito intenso\u201d, conta um homem.<\/p>\n<p>\u201cTodo lugar que voc\u00ea vai voc\u00ea v\u00ea policial, voc\u00ea v\u00ea gente com rosto tampado\u201d, diz uma mulher .<\/p>\n<p>Os manifestantes come\u00e7aram a se dispersar, mas os confrontos continuaram.<\/p>\n<p>Ap\u00f3s uma hora de confronto na Consola\u00e7\u00e3o, de um lado os manifestantes, que estavam mais dispersos, e de outro a pol\u00edcia, com g\u00e1s lacrimog\u00eaneo, bombas de pimenta e balas de borracha.<\/p>\n<p>Mais um momento tenso no confronto da pol\u00edcia com os manifestantes. Os manifestantes desceram em dire\u00e7\u00e3o \u00e0 cavalaria da Pol\u00edcia Militar, que estava posicionada na Rua da Consola\u00e7\u00e3o. J\u00e1 eram quase duas horas de confronto. Os manifestantes iam com os bra\u00e7os levantados.<\/p>\n<p>Alguns manifestantes encararam os policiais: \u201cVoc\u00eas s\u00e3o cidad\u00e3os antes de pol\u00edcia!\u201d, diz uma menina.<\/p>\n<p>Um jovem foi atingido por bala de borracha a uma curta dist\u00e2ncia. Uma rep\u00f3rter do jornal Folha de S\u00e3o Paulo foi atingida por uma bala de borracha da tropa de choque. O jornal diz que outros seis profissionais tamb\u00e9m ficaram feridos. Entre eles, um fot\u00f3grafo.<\/p>\n<p>O clima tenso continuou em outros pontos da cidade. Na Avenida Doutor Arnaldo, uma importante avenida da capital paulista, uma regi\u00e3o de muitos hospitais, como Hospital do Cora\u00e7\u00e3o, Hospital Emilio Ribas, gente voltando do trabalho, tropa de choque, manifestantes, uma cena impressionante.<\/p>\n<p>O protesto continuou na Avenida Paulista, por onde j\u00e1 tinham passado as outras tr\u00eas manifesta\u00e7\u00f5es pela redu\u00e7\u00e3o da tarifa. At\u00e9 quem voltava para casa, dentro dos \u00f4nibus, sofreu com o g\u00e1s pimenta.<\/p>\n<p>Em um bar, a pol\u00edcia deu ordem para as pessoas sa\u00edrem. \u201cChegaram na borrachada, mandando fechar o bar. Se eu quisesse fazer uma queixa como um cidad\u00e3o comum conta um policial pela forma que ele me tratou eu posso, porque ele n\u00e3o tem identifica\u00e7\u00e3o nem a patente que ele tem\u201d, diz um homem.<\/p>\n<p>\u201cA a\u00e7\u00e3o da pol\u00edcia foi extremamente desproporcional e \u00e9 prova de que o movimento pac\u00edfico est\u00e1 sendo duramente reprimido\u201d, declara a ativista Mayara Vivian.<\/p>\n<p>\u201cA Pol\u00edcia Militar tem o dever legal de agir, e n\u00f3s estamos agindo e vamos agir sempre que se fizer necess\u00e1rio\u201d, declara um policial.<\/p>\n<p>A Secretaria de Seguran\u00e7a P\u00fablica disse que vai investigar a a\u00e7\u00e3o da PM no protesto desta quinta. Autoridades falaram sobre a viol\u00eancia das manifesta\u00e7\u00f5es na cidade.<\/p>\n<p>O secret\u00e1rio da Seguran\u00e7a P\u00fablica de S\u00e3o Paulo, Fernando Grella Vieira, determinou a abertura imediata de investiga\u00e7\u00f5es, pela corregedoria da PM, para apurar os fatos envolvendo agress\u00f5es de policiais militares a manifestantes e jornalistas.<\/p>\n<p>Enquanto o protesto acontecia, o porta-voz da Pol\u00edcia Militar falou sobre o direito de manifesta\u00e7\u00e3o da popula\u00e7\u00e3o. \u201cA Policia Militar faz com que haja o direito de manifesta\u00e7\u00e3o legitima\u201d, afirma Marcel Soffner<\/p>\n<p>\u201cO que a gente percebe \u00e9 que \u00e9 um movimento pol\u00edtico, pequeno, mas muito violento?\u201d, diz Geraldo Alckmin, quee nega a cogita\u00e7\u00e3o \u00e0 redu\u00e7\u00e3o de tarifas.<\/p>\n<p>Em entrevista coletiva, o prefeito Fernando Haddad tamb\u00e9m negou que haver\u00e1 redu\u00e7\u00e3o das tarifas e repudiou a viol\u00eancia. \u201cS\u00e3o Paulo est\u00e1 acostumada com manifesta\u00e7\u00f5es. N\u00e3o \u00e9 novidade para a cidade de S\u00e3o Paulo. O que a cidade n\u00e3o aceita \u00e9 a forma violenta de se manifestar e se expressar. Com isso, a cidade n\u00e3o compactua. O valor ser\u00e1 mantido porque ele est\u00e1 muito abaixo da infla\u00e7\u00e3o acumulada\u201d, declara Haddad.<\/p>\n<p>\u201cEu acho que S\u00e3o Paulo convive muito bem com a educa\u00e7\u00e3o pac\u00edfica, com manifesta\u00e7\u00f5es, com protestos, com contesta\u00e7\u00f5es, mas n\u00e3o convive bem com a viol\u00eancia. Quando h\u00e1 viol\u00eancia por parte dos manifestantes, como foi o caso do policial agredido, a popula\u00e7\u00e3o repudiou. Quando h\u00e1 o abuso policial, tamb\u00e9m a popula\u00e7\u00e3o repudia\u201d, declarou o prefeito Fernando Haddad.<\/p>\n<p>O ministro da Justi\u00e7a, Jos\u00e9 Eduardo Cardozo, ofereceu ajuda ao prefeito e ao governador e colocou o Governo Federal \u00e0 disposi\u00e7\u00e3o para o que for necess\u00e1rio.<\/p>\n<p>O prefeito Fernando Haddad disse que a tarifa foi ajustada abaixo da infla\u00e7\u00e3o, que o subs\u00eddio ao sistema de \u00f4nibus \u00e9 de R$ 600 milh\u00f5es e que n\u00e3o haver\u00e1 redu\u00e7\u00e3o de tarifa.<\/p>\n<p><em>Fonte: G1<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Uma noite de viol\u00eancia e p\u00e2nico na cidade de S\u00e3o Paulo. O quarto dia de protestos contra o aumento da tarifa do transporte p\u00fablico transformou as ruas da maior cidade do pa\u00eds em um cen\u00e1rio de guerra. Foram seis horas de protesto. Dessa vez, a pol\u00edcia endureceu a repress\u00e3o, agindo com viol\u00eancia. Duzentas pessoas foram detidas e dezenas ficaram feridas. Muita gente que n\u00e3o fazia parte do protesto tamb\u00e9m ficou no meio de tiros e pedras. No quarto dia de protestos contra o aumento da tarifa de \u00f4nibus, a repress\u00e3o policial foi mais intensa. Uma noite que terminou com mais <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1646","post","type-post","status-publish","format-standard","hentry","category-noticias-no-centro-sp"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Uma noite de viol\u00eancia e p\u00e2nico na cidade de S\u00e3o Paulo. O quarto dia de protestos contra o aumento da tarifa do transporte p\u00fablico transformou as ruas da maior cidade do pa\u00eds em um cen\u00e1rio de guerra. Foram seis horas de protesto. Dessa vez, a pol\u00edcia endureceu a repress\u00e3o, agindo com viol\u00eancia. Duzentas pessoas foram\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Encontra Centro SP\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Encontra Centro SP | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pol\u00edcia Militar utiliza viol\u00eancia para reprimir protesto no Centro de S\u00e3o Paulo | Encontra Centro SP\" \/>\n\t\t<meta property=\"og:description\" content=\"Uma noite de viol\u00eancia e p\u00e2nico na cidade de S\u00e3o Paulo. O quarto dia de protestos contra o aumento da tarifa do transporte p\u00fablico transformou as ruas da maior cidade do pa\u00eds em um cen\u00e1rio de guerra. Foram seis horas de protesto. Dessa vez, a pol\u00edcia endureceu a repress\u00e3o, agindo com viol\u00eancia. Duzentas pessoas foram\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-06-14T17:17:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-29T19:20:05+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pol\u00edcia Militar utiliza viol\u00eancia para reprimir protesto no Centro de S\u00e3o Paulo | Encontra Centro SP\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Uma noite de viol\u00eancia e p\u00e2nico na cidade de S\u00e3o Paulo. O quarto dia de protestos contra o aumento da tarifa do transporte p\u00fablico transformou as ruas da maior cidade do pa\u00eds em um cen\u00e1rio de guerra. Foram seis horas de protesto. Dessa vez, a pol\u00edcia endureceu a repress\u00e3o, agindo com viol\u00eancia. Duzentas pessoas foram\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\\\/#article\",\"name\":\"Pol\\u00edcia Militar utiliza viol\\u00eancia para reprimir protesto no Centro de S\\u00e3o Paulo | Encontra Centro SP\",\"headline\":\"Pol\\u00edcia Militar utiliza viol\\u00eancia para reprimir protesto no Centro de S\\u00e3o Paulo\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\"},\"datePublished\":\"2013-06-14T15:17:37-03:00\",\"dateModified\":\"2019-04-29T16:20:05-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias Centro SP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"name\":\"Not\\u00edcias Centro SP\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias Centro SP\",\"item\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\\\/#listItem\",\"name\":\"Pol\\u00edcia Militar utiliza viol\\u00eancia para reprimir protesto no Centro de S\\u00e3o Paulo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\\\/#listItem\",\"position\":3,\"name\":\"Pol\\u00edcia Militar utiliza viol\\u00eancia para reprimir protesto no Centro de S\\u00e3o Paulo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"name\":\"Not\\u00edcias Centro SP\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\",\"name\":\"Encontra Centro SP\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Centro SP e regi\\u00e3o.\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/\",\"name\":\"Encontra Centro SP\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Encontra Centro SP\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\\\/#webpage\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\\\/\",\"name\":\"Pol\\u00edcia Militar utiliza viol\\u00eancia para reprimir protesto no Centro de S\\u00e3o Paulo | Encontra Centro SP\",\"description\":\"Uma noite de viol\\u00eancia e p\\u00e2nico na cidade de S\\u00e3o Paulo. O quarto dia de protestos contra o aumento da tarifa do transporte p\\u00fablico transformou as ruas da maior cidade do pa\\u00eds em um cen\\u00e1rio de guerra. Foram seis horas de protesto. Dessa vez, a pol\\u00edcia endureceu a repress\\u00e3o, agindo com viol\\u00eancia. Duzentas pessoas foram\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"datePublished\":\"2013-06-14T15:17:37-03:00\",\"dateModified\":\"2019-04-29T16:20:05-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/\",\"name\":\"Encontra Centro SP\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Centro SP e regi\\u00e3o.\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Pol\u00edcia Militar utiliza viol\u00eancia para reprimir protesto no Centro de S\u00e3o Paulo | Encontra Centro SP","description":"Uma noite de viol\u00eancia e p\u00e2nico na cidade de S\u00e3o Paulo. O quarto dia de protestos contra o aumento da tarifa do transporte p\u00fablico transformou as ruas da maior cidade do pa\u00eds em um cen\u00e1rio de guerra. Foram seis horas de protesto. Dessa vez, a pol\u00edcia endureceu a repress\u00e3o, agindo com viol\u00eancia. Duzentas pessoas foram","canonical_url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\/#article","name":"Pol\u00edcia Militar utiliza viol\u00eancia para reprimir protesto no Centro de S\u00e3o Paulo | Encontra Centro SP","headline":"Pol\u00edcia Militar utiliza viol\u00eancia para reprimir protesto no Centro de S\u00e3o Paulo","author":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"publisher":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization"},"datePublished":"2013-06-14T15:17:37-03:00","dateModified":"2019-04-29T16:20:05-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\/#webpage"},"isPartOf":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\/#webpage"},"articleSection":"Not\u00edcias Centro SP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","name":"Not\u00edcias Centro SP"}},{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","position":2,"name":"Not\u00edcias Centro SP","item":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\/#listItem","name":"Pol\u00edcia Militar utiliza viol\u00eancia para reprimir protesto no Centro de S\u00e3o Paulo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\/#listItem","position":3,"name":"Pol\u00edcia Militar utiliza viol\u00eancia para reprimir protesto no Centro de S\u00e3o Paulo","previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","name":"Not\u00edcias Centro SP"}}]},{"@type":"Organization","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization","name":"Encontra Centro SP","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/"},{"@type":"Person","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/","name":"Encontra Centro SP","image":{"@type":"ImageObject","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","width":96,"height":96,"caption":"Encontra Centro SP"}},{"@type":"WebPage","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\/#webpage","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\/","name":"Pol\u00edcia Militar utiliza viol\u00eancia para reprimir protesto no Centro de S\u00e3o Paulo | Encontra Centro SP","description":"Uma noite de viol\u00eancia e p\u00e2nico na cidade de S\u00e3o Paulo. O quarto dia de protestos contra o aumento da tarifa do transporte p\u00fablico transformou as ruas da maior cidade do pa\u00eds em um cen\u00e1rio de guerra. Foram seis horas de protesto. Dessa vez, a pol\u00edcia endureceu a repress\u00e3o, agindo com viol\u00eancia. Duzentas pessoas foram","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#website"},"breadcrumb":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\/#breadcrumblist"},"author":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"creator":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"datePublished":"2013-06-14T15:17:37-03:00","dateModified":"2019-04-29T16:20:05-03:00"},{"@type":"WebSite","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#website","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/","name":"Encontra Centro SP","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Encontra Centro SP | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","og:type":"article","og:title":"Pol\u00edcia Militar utiliza viol\u00eancia para reprimir protesto no Centro de S\u00e3o Paulo | Encontra Centro SP","og:description":"Uma noite de viol\u00eancia e p\u00e2nico na cidade de S\u00e3o Paulo. O quarto dia de protestos contra o aumento da tarifa do transporte p\u00fablico transformou as ruas da maior cidade do pa\u00eds em um cen\u00e1rio de guerra. Foram seis horas de protesto. Dessa vez, a pol\u00edcia endureceu a repress\u00e3o, agindo com viol\u00eancia. Duzentas pessoas foram","og:url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\/","article:published_time":"2013-06-14T17:17:37+00:00","article:modified_time":"2019-04-29T19:20:05+00:00","twitter:card":"summary","twitter:title":"Pol\u00edcia Militar utiliza viol\u00eancia para reprimir protesto no Centro de S\u00e3o Paulo | Encontra Centro SP","twitter:description":"Uma noite de viol\u00eancia e p\u00e2nico na cidade de S\u00e3o Paulo. O quarto dia de protestos contra o aumento da tarifa do transporte p\u00fablico transformou as ruas da maior cidade do pa\u00eds em um cen\u00e1rio de guerra. Foram seis horas de protesto. Dessa vez, a pol\u00edcia endureceu a repress\u00e3o, agindo com viol\u00eancia. Duzentas pessoas foram"},"aioseo_meta_data":{"post_id":"1646","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-18 18:53:38","updated":"2025-11-17 22:08:52","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/\" title=\"Not\u00edcias Centro SP\">Not\u00edcias Centro SP<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPol\u00edcia Militar utiliza viol\u00eancia para reprimir protesto no Centro de S\u00e3o Paulo\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre"},{"label":"Not\u00edcias Centro SP","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/"},{"label":"Pol\u00edcia Militar utiliza viol\u00eancia para reprimir protesto no Centro de S\u00e3o Paulo","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/policia-militar-utiliza-violencia-para-reprimir-protesto-no-centro-de-sao-paulo\/"}],"_links":{"self":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=1646"}],"version-history":[{"count":0,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1646\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=1646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=1646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=1646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}