{"id":1737,"date":"2013-06-25T10:21:57","date_gmt":"2013-06-25T12:21:57","guid":{"rendered":"http:\/\/www.encontracentrosaopaulo.com.br\/noticias\/?p=1737"},"modified":"2019-04-29T16:20:05","modified_gmt":"2019-04-29T19:20:05","slug":"recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo","status":"publish","type":"post","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\/","title":{"rendered":"Recreio nas F\u00e9rias tem passeios no Centro de S\u00e3o Paulo"},"content":{"rendered":"<div class=\"d6585b5127f45a35450431d0abc3f90c\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>As f\u00e9rias j\u00e1 come\u00e7aram e, junto com elas, as inscri\u00e7\u00f5es para as atividades do Recreio nas F\u00e9rias, um projeto da prefeitura que acontece no m\u00eas de julho em toda a cidade . Dentre os dias 15 e 19 a molecada ter\u00e1 centenas de atividades esportivas e culturais.<\/p>\n<p>S\u00e3o cerca de 674 passeios gratuitos a museus, teatros e parques. Na regi\u00e3o central da cidade os pequenos poder\u00e3o visitar o Espa\u00e7o Cultural Catavento, SESC Consola\u00e7\u00e3o, Museu do Futebol, entre outros, com direito a refei\u00e7\u00f5es e lanches.<\/p>\n<p>Para participar, n\u00e3o \u00e9 preciso ser especificamente aluno de uma escola municipal, basta ser aluno de alguma rede de ensino. Os interessados em fazer a inscri\u00e7\u00e3o devem apresentar autoriza\u00e7\u00e3o assinada pelos pais. O projeto atende crian\u00e7as e jovens de quatro a quatorze anos.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Veja os locais da regi\u00e3o central da cidade:<\/strong><\/span><strong><br \/>\n<\/strong><\/p>\n<p><strong>Espa\u00e7o Cultural Catavento<\/strong><br \/>\nHor\u00e1rio de funcionamento: ter\u00e7a-feira a domingo, das 9h \u00e0s 17 horas.<br \/>\nEndere\u00e7o: Pra\u00e7a C\u00edvica Ulisses Guimar\u00e3es, s\/n &#8211; Parque Dom Pedro II<br \/>\nSite: cataventocultural.org.br\/<\/p>\n<p><strong>CINESESC<\/strong><br \/>\nHor\u00e1rio de funcionamento: todos os dias, inclusive feriados, 13h40 \u00e0s 21h30<br \/>\nEndere\u00e7o: rua Augusta, 2075<br \/>\nTelefone: 3087-0500<br \/>\nSite: sescsp.org.br<\/p>\n<p><strong>Museu da L\u00edngua Portuguesa<\/strong><br \/>\nHor\u00e1rio de Funcionamento: ter\u00e7a-feira das 10h \u00e0s 22h; quarta-feira a domingo das 10h \u00e0s 18 horas.<br \/>\nEndere\u00e7o: Pra\u00e7a da Luz, s\/n\u00ba Centro<br \/>\nTelefone: 3322-0080<br \/>\nSite: museulinguaportuguesa.org.br\/<\/p>\n<p><strong>Museu do Futebol<\/strong><br \/>\nEndere\u00e7o: Pra\u00e7a Charles Miller, S\/N &#8211; Est\u00e1dio do Pacaembu<br \/>\nS\u00e3o Paulo &#8211; (55) 11 3664-3848<br \/>\nSite: museudofutebol.org.br<\/p>\n<p><strong>Theatro Municipal<\/strong><br \/>\nEndere\u00e7o: Pra\u00e7a Ramos de Azevedo, s\/n\u00ba<br \/>\nTelefone +5511 3397.0300\/ Bilheteria +5511 3397.0327<br \/>\nSite: prefeitura.sp.gov.br<\/p>\n<p><strong>SESC Bom Retiro<\/strong><br \/>\nHor\u00e1rio de Funcionamento: ter\u00e7a a sexta, das 9h \u00e0s 20h30; s\u00e1bado, das 10h \u00e0s 18h30; domingo e feriados, das 10h \u00e0s 17h30.<br \/>\nEndere\u00e7o: Alameda Nothmann, 185 &#8211; Bom Retiro<br \/>\nTelefone: 3332-3600<br \/>\nSite: sescsp.org.br<\/p>\n<p><strong>SESC Consola\u00e7\u00e3o<\/strong><br \/>\nHor\u00e1rio de Funcionamento: segunda a sexta, das 7h \u00e0s 22h; s\u00e1bados e feriados (exceto domingos), das 10h \u00e0s 19h.<br \/>\nEndere\u00e7o: rua Dr. Vila Nova, 245 &#8211; Consola\u00e7\u00e3o<br \/>\nSite: sescsp.org.br<\/p>\n<p><em>Fonte: Prefeitura de S. Paulo<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>As f\u00e9rias j\u00e1 come\u00e7aram e, junto com elas, as inscri\u00e7\u00f5es para as atividades do Recreio nas F\u00e9rias, um projeto da prefeitura que acontece no m\u00eas de julho em toda a cidade . Dentre os dias 15 e 19 a molecada ter\u00e1 centenas de atividades esportivas e culturais. S\u00e3o cerca de 674 passeios gratuitos a museus, teatros e parques. Na regi\u00e3o central da cidade os pequenos poder\u00e3o visitar o Espa\u00e7o Cultural Catavento, SESC Consola\u00e7\u00e3o, Museu do Futebol, entre outros, com direito a refei\u00e7\u00f5es e lanches. Para participar, n\u00e3o \u00e9 preciso ser especificamente aluno de uma escola municipal, basta ser aluno de <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1737","post","type-post","status-publish","format-standard","hentry","category-noticias-no-centro-sp"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"As f\u00e9rias j\u00e1 come\u00e7aram e, junto com elas, as inscri\u00e7\u00f5es para as atividades do Recreio nas F\u00e9rias, um projeto da prefeitura que acontece no m\u00eas de julho em toda a cidade . Dentre os dias 15 e 19 a molecada ter\u00e1 centenas de atividades esportivas e culturais. S\u00e3o cerca de 674 passeios gratuitos a museus,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Encontra Centro SP\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Encontra Centro SP | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Recreio nas F\u00e9rias tem passeios no Centro de S\u00e3o Paulo | Encontra Centro SP\" \/>\n\t\t<meta property=\"og:description\" content=\"As f\u00e9rias j\u00e1 come\u00e7aram e, junto com elas, as inscri\u00e7\u00f5es para as atividades do Recreio nas F\u00e9rias, um projeto da prefeitura que acontece no m\u00eas de julho em toda a cidade . Dentre os dias 15 e 19 a molecada ter\u00e1 centenas de atividades esportivas e culturais. S\u00e3o cerca de 674 passeios gratuitos a museus,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-06-25T12:21:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-29T19:20:05+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Recreio nas F\u00e9rias tem passeios no Centro de S\u00e3o Paulo | Encontra Centro SP\" \/>\n\t\t<meta name=\"twitter:description\" content=\"As f\u00e9rias j\u00e1 come\u00e7aram e, junto com elas, as inscri\u00e7\u00f5es para as atividades do Recreio nas F\u00e9rias, um projeto da prefeitura que acontece no m\u00eas de julho em toda a cidade . Dentre os dias 15 e 19 a molecada ter\u00e1 centenas de atividades esportivas e culturais. S\u00e3o cerca de 674 passeios gratuitos a museus,\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\\\/#article\",\"name\":\"Recreio nas F\\u00e9rias tem passeios no Centro de S\\u00e3o Paulo | Encontra Centro SP\",\"headline\":\"Recreio nas F\\u00e9rias tem passeios no Centro de S\\u00e3o Paulo\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\"},\"datePublished\":\"2013-06-25T10:21:57-03:00\",\"dateModified\":\"2019-04-29T16:20:05-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias Centro SP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"name\":\"Not\\u00edcias Centro SP\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias Centro SP\",\"item\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\\\/#listItem\",\"name\":\"Recreio nas F\\u00e9rias tem passeios no Centro de S\\u00e3o Paulo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\\\/#listItem\",\"position\":3,\"name\":\"Recreio nas F\\u00e9rias tem passeios no Centro de S\\u00e3o Paulo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"name\":\"Not\\u00edcias Centro SP\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\",\"name\":\"Encontra Centro SP\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Centro SP e regi\\u00e3o.\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/\",\"name\":\"Encontra Centro SP\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Encontra Centro SP\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\\\/#webpage\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\\\/\",\"name\":\"Recreio nas F\\u00e9rias tem passeios no Centro de S\\u00e3o Paulo | Encontra Centro SP\",\"description\":\"As f\\u00e9rias j\\u00e1 come\\u00e7aram e, junto com elas, as inscri\\u00e7\\u00f5es para as atividades do Recreio nas F\\u00e9rias, um projeto da prefeitura que acontece no m\\u00eas de julho em toda a cidade . Dentre os dias 15 e 19 a molecada ter\\u00e1 centenas de atividades esportivas e culturais. S\\u00e3o cerca de 674 passeios gratuitos a museus,\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"datePublished\":\"2013-06-25T10:21:57-03:00\",\"dateModified\":\"2019-04-29T16:20:05-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/\",\"name\":\"Encontra Centro SP\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Centro SP e regi\\u00e3o.\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Recreio nas F\u00e9rias tem passeios no Centro de S\u00e3o Paulo | Encontra Centro SP","description":"As f\u00e9rias j\u00e1 come\u00e7aram e, junto com elas, as inscri\u00e7\u00f5es para as atividades do Recreio nas F\u00e9rias, um projeto da prefeitura que acontece no m\u00eas de julho em toda a cidade . Dentre os dias 15 e 19 a molecada ter\u00e1 centenas de atividades esportivas e culturais. S\u00e3o cerca de 674 passeios gratuitos a museus,","canonical_url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\/#article","name":"Recreio nas F\u00e9rias tem passeios no Centro de S\u00e3o Paulo | Encontra Centro SP","headline":"Recreio nas F\u00e9rias tem passeios no Centro de S\u00e3o Paulo","author":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"publisher":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization"},"datePublished":"2013-06-25T10:21:57-03:00","dateModified":"2019-04-29T16:20:05-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\/#webpage"},"isPartOf":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\/#webpage"},"articleSection":"Not\u00edcias Centro SP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","name":"Not\u00edcias Centro SP"}},{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","position":2,"name":"Not\u00edcias Centro SP","item":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\/#listItem","name":"Recreio nas F\u00e9rias tem passeios no Centro de S\u00e3o Paulo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\/#listItem","position":3,"name":"Recreio nas F\u00e9rias tem passeios no Centro de S\u00e3o Paulo","previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","name":"Not\u00edcias Centro SP"}}]},{"@type":"Organization","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization","name":"Encontra Centro SP","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/"},{"@type":"Person","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/","name":"Encontra Centro SP","image":{"@type":"ImageObject","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","width":96,"height":96,"caption":"Encontra Centro SP"}},{"@type":"WebPage","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\/#webpage","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\/","name":"Recreio nas F\u00e9rias tem passeios no Centro de S\u00e3o Paulo | Encontra Centro SP","description":"As f\u00e9rias j\u00e1 come\u00e7aram e, junto com elas, as inscri\u00e7\u00f5es para as atividades do Recreio nas F\u00e9rias, um projeto da prefeitura que acontece no m\u00eas de julho em toda a cidade . Dentre os dias 15 e 19 a molecada ter\u00e1 centenas de atividades esportivas e culturais. S\u00e3o cerca de 674 passeios gratuitos a museus,","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#website"},"breadcrumb":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\/#breadcrumblist"},"author":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"creator":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"datePublished":"2013-06-25T10:21:57-03:00","dateModified":"2019-04-29T16:20:05-03:00"},{"@type":"WebSite","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#website","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/","name":"Encontra Centro SP","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Encontra Centro SP | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","og:type":"article","og:title":"Recreio nas F\u00e9rias tem passeios no Centro de S\u00e3o Paulo | Encontra Centro SP","og:description":"As f\u00e9rias j\u00e1 come\u00e7aram e, junto com elas, as inscri\u00e7\u00f5es para as atividades do Recreio nas F\u00e9rias, um projeto da prefeitura que acontece no m\u00eas de julho em toda a cidade . Dentre os dias 15 e 19 a molecada ter\u00e1 centenas de atividades esportivas e culturais. S\u00e3o cerca de 674 passeios gratuitos a museus,","og:url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\/","article:published_time":"2013-06-25T12:21:57+00:00","article:modified_time":"2019-04-29T19:20:05+00:00","twitter:card":"summary","twitter:title":"Recreio nas F\u00e9rias tem passeios no Centro de S\u00e3o Paulo | Encontra Centro SP","twitter:description":"As f\u00e9rias j\u00e1 come\u00e7aram e, junto com elas, as inscri\u00e7\u00f5es para as atividades do Recreio nas F\u00e9rias, um projeto da prefeitura que acontece no m\u00eas de julho em toda a cidade . Dentre os dias 15 e 19 a molecada ter\u00e1 centenas de atividades esportivas e culturais. S\u00e3o cerca de 674 passeios gratuitos a museus,"},"aioseo_meta_data":{"post_id":"1737","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-18 18:52:10","updated":"2025-11-17 23:10:33","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/\" title=\"Not\u00edcias Centro SP\">Not\u00edcias Centro SP<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRecreio nas F\u00e9rias tem passeios no Centro de S\u00e3o Paulo\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre"},{"label":"Not\u00edcias Centro SP","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/"},{"label":"Recreio nas F\u00e9rias tem passeios no Centro de S\u00e3o Paulo","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/recreio-nas-ferias-tem-passeios-no-centro-de-sao-paulo\/"}],"_links":{"self":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=1737"}],"version-history":[{"count":0,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1737\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=1737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=1737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=1737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}