{"id":1780,"date":"2013-07-10T13:21:56","date_gmt":"2013-07-10T15:21:56","guid":{"rendered":"http:\/\/www.encontracentrosaopaulo.com.br\/noticias\/?p=1780"},"modified":"2019-04-29T16:20:04","modified_gmt":"2019-04-29T19:20:04","slug":"sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha","status":"publish","type":"post","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\/","title":{"rendered":"Sindicalistas prometem fechar todos os terminais de SP amanh\u00e3"},"content":{"rendered":"<div class=\"d6585b5127f45a35450431d0abc3f90c\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Os sindicalistas que bloquearam 15 terminais de \u00f4nibus nesta quarta-feira prometem fechar todos os 31 terminais da cidade a partir das 9h de amanh\u00e3. O grupo faz parte de uma chapa de oposi\u00e7\u00e3o no sindicato dos motorista e cobradores de S\u00e3o Paulo.<\/p>\n<p>Eles v\u00e3o aderir ao &#8220;Dia Nacional de Lutas&#8221;, movimento de centrais sindicais que pretende paralisar S\u00e3o Paulo e algumas das principais cidades do pa\u00eds amanh\u00e3. As centrais sindicais devem se reunir em frente ao Masp, na avenida Paulista, a partir das 12h.<\/p>\n<p>&#8220;\u00c9 preciso que os trabalhadores discutam os seus interesses e \u00e9 isso que vamos fazer&#8221;, diz Edivaldo Santiago, candidato a vice-presidente na chapa de oposi\u00e7\u00e3o no sindicato. A elei\u00e7\u00e3o ocorre nesta semana.<\/p>\n<p>Segundo o sindicalista, haver\u00e1 uma grande mobiliza\u00e7\u00e3o em todos os terminais. &#8220;Vamos parar por volta das 9h. Vamos atender as linhas que v\u00e3o at\u00e9 a avenida Paulista para n\u00e3o desmobilizar o grande ato do Masp.&#8221;<\/p>\n<p>Hoje, os sindicalistas fecharam os terminais gradativamente a partir das 8h. Passageiros conseguem entrar, mas os \u00f4nibus n\u00e3o podem sair.<\/p>\n<p>Segundo a SPTrans, empresa municipal de transporte, continuam bloqueados os terminais Santo Amaro, Parque D. Pedro, Capelinha, Campo Limpo, Graja\u00fa, Varginha, Jo\u00e3o Dias, Lapa, Cachoeirinha, Pirituba, Casa Verde, Vila Prudente, metr\u00f4 Santana, Sacom\u00e3 e Mercado, do Expresso Tiradentes.<\/p>\n<p>Atualmente, o presidente do sindicato dos motoristas e cobradores \u00e9 Isao Hosogi. Ele condenou os bloqueios e disse que uma &#8220;minoria dissente pratica terror eleitoral&#8221;.<\/p>\n<p>Edivaldo Santiago, no entanto, negou que os atos de hoje tenham rela\u00e7\u00e3o com a elei\u00e7\u00e3o. &#8220;Os bloqueios n\u00e3o t\u00eam nada a ver com a elei\u00e7\u00e3o. O trabalhador tem de vir em primeiro lugar&#8221;, disse.<\/p>\n<p>Ainda de acordo com ele, os sindicalistas s\u00f3 saem ap\u00f3s manifesta\u00e7\u00e3o da prefeitura sobre as reivindica\u00e7\u00f5es do grupo. Eles querem melhores condi\u00e7\u00f5es de trabalho e garantia de emprego a cobradores.<\/p>\n<p>No dia 3, o mesmo grupo bloqueou tr\u00eas terminais na cidade por duas horas e meia.<\/p>\n<p>&#8220;\u00c9 um absurdo que uma disputa sindical afete a vida do trabalhador de S\u00e3o Paulo&#8221;, diz Jilmar Tatto, secret\u00e1rio municipal dos Transportes.<\/p>\n<p><b>DISPUTA<\/b><\/p>\n<p>O principal articulador da chapa de oposi\u00e7\u00e3o na elei\u00e7\u00e3o do sindicato dos motoristas e cobradores de \u00f4nibus \u00e9 Edivaldo Santiago, 65, que liderou a maior greve de \u00f4nibus da hist\u00f3ria de S\u00e3o Paulo.<\/p>\n<p>Ele era presidente do sindicato em 1992, quando os ve\u00edculos ainda eram da CMTC (empresa municipal) e ficaram nove dias parados.<\/p>\n<p>&#8220;Nenhum partido nos representa. Somos contra essa atual administra\u00e7\u00e3o do sindicato, que \u00e9 conivente com os patr\u00f5es e se vende para a prefeitura&#8221;, disse Santiago ao participar do protesto da semana passada. Ele \u00e9 candidato a vice-presidente na chapa da oposi\u00e7\u00e3o.<\/p>\n<p>Santiago \u00e9 criticado por opositores por n\u00e3o ter endurecido na gest\u00e3o Maluf, quando a CMTC foi extinta.<\/p>\n<p>Voltou ao sindicato em 2000. Ele e outros 18 integrantes da diretoria foram presos em 2003 sob a acusa\u00e7\u00e3o de crimes como enriquecimento il\u00edcito e forma\u00e7\u00e3o de quadrilha -negada por eles.<\/p>\n<p>Entre os presos tamb\u00e9m estava o atual presidente, Isao Hosogi, o Jorginho, e o diretor financeiro, Jos\u00e9 Valdevan de Jesus, o Valdevan Noventa.<\/p>\n<p>Libertado, Jorginho assumiu no ano seguinte por influ\u00eancia de Santiago, a quem chamava de &#8220;padrinho&#8221;.<\/p>\n<p>Mas disputas acabaram com a alian\u00e7a de d\u00e9cadas.<\/p>\n<p><em>Fonte: Folha de S. Paulo<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Os sindicalistas que bloquearam 15 terminais de \u00f4nibus nesta quarta-feira prometem fechar todos os 31 terminais da cidade a partir das 9h de amanh\u00e3. O grupo faz parte de uma chapa de oposi\u00e7\u00e3o no sindicato dos motorista e cobradores de S\u00e3o Paulo. Eles v\u00e3o aderir ao &#8220;Dia Nacional de Lutas&#8221;, movimento de centrais sindicais que pretende paralisar S\u00e3o Paulo e algumas das principais cidades do pa\u00eds amanh\u00e3. As centrais sindicais devem se reunir em frente ao Masp, na avenida Paulista, a partir das 12h. &#8220;\u00c9 preciso que os trabalhadores discutam os seus interesses e \u00e9 isso que vamos fazer&#8221;, diz <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1780","post","type-post","status-publish","format-standard","hentry","category-noticias-no-centro-sp"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Os sindicalistas que bloquearam 15 terminais de \u00f4nibus nesta quarta-feira prometem fechar todos os 31 terminais da cidade a partir das 9h de amanh\u00e3. O grupo faz parte de uma chapa de oposi\u00e7\u00e3o no sindicato dos motorista e cobradores de S\u00e3o Paulo. Eles v\u00e3o aderir ao &quot;Dia Nacional de Lutas&quot;, movimento de centrais sindicais que\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Encontra Centro SP\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Encontra Centro SP | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sindicalistas prometem fechar todos os terminais de SP amanh\u00e3 | Encontra Centro SP\" \/>\n\t\t<meta property=\"og:description\" content=\"Os sindicalistas que bloquearam 15 terminais de \u00f4nibus nesta quarta-feira prometem fechar todos os 31 terminais da cidade a partir das 9h de amanh\u00e3. O grupo faz parte de uma chapa de oposi\u00e7\u00e3o no sindicato dos motorista e cobradores de S\u00e3o Paulo. Eles v\u00e3o aderir ao &quot;Dia Nacional de Lutas&quot;, movimento de centrais sindicais que\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-07-10T15:21:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-29T19:20:04+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sindicalistas prometem fechar todos os terminais de SP amanh\u00e3 | Encontra Centro SP\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Os sindicalistas que bloquearam 15 terminais de \u00f4nibus nesta quarta-feira prometem fechar todos os 31 terminais da cidade a partir das 9h de amanh\u00e3. O grupo faz parte de uma chapa de oposi\u00e7\u00e3o no sindicato dos motorista e cobradores de S\u00e3o Paulo. Eles v\u00e3o aderir ao &quot;Dia Nacional de Lutas&quot;, movimento de centrais sindicais que\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\\\/#article\",\"name\":\"Sindicalistas prometem fechar todos os terminais de SP amanh\\u00e3 | Encontra Centro SP\",\"headline\":\"Sindicalistas prometem fechar todos os terminais de SP amanh\\u00e3\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\"},\"datePublished\":\"2013-07-10T13:21:56-03:00\",\"dateModified\":\"2019-04-29T16:20:04-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias Centro SP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"name\":\"Not\\u00edcias Centro SP\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias Centro SP\",\"item\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\\\/#listItem\",\"name\":\"Sindicalistas prometem fechar todos os terminais de SP amanh\\u00e3\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\\\/#listItem\",\"position\":3,\"name\":\"Sindicalistas prometem fechar todos os terminais de SP amanh\\u00e3\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"name\":\"Not\\u00edcias Centro SP\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\",\"name\":\"Encontra Centro SP\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Centro SP e regi\\u00e3o.\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/\",\"name\":\"Encontra Centro SP\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Encontra Centro SP\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\\\/#webpage\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\\\/\",\"name\":\"Sindicalistas prometem fechar todos os terminais de SP amanh\\u00e3 | Encontra Centro SP\",\"description\":\"Os sindicalistas que bloquearam 15 terminais de \\u00f4nibus nesta quarta-feira prometem fechar todos os 31 terminais da cidade a partir das 9h de amanh\\u00e3. O grupo faz parte de uma chapa de oposi\\u00e7\\u00e3o no sindicato dos motorista e cobradores de S\\u00e3o Paulo. Eles v\\u00e3o aderir ao \\\"Dia Nacional de Lutas\\\", movimento de centrais sindicais que\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"datePublished\":\"2013-07-10T13:21:56-03:00\",\"dateModified\":\"2019-04-29T16:20:04-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/\",\"name\":\"Encontra Centro SP\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Centro SP e regi\\u00e3o.\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sindicalistas prometem fechar todos os terminais de SP amanh\u00e3 | Encontra Centro SP","description":"Os sindicalistas que bloquearam 15 terminais de \u00f4nibus nesta quarta-feira prometem fechar todos os 31 terminais da cidade a partir das 9h de amanh\u00e3. O grupo faz parte de uma chapa de oposi\u00e7\u00e3o no sindicato dos motorista e cobradores de S\u00e3o Paulo. Eles v\u00e3o aderir ao \"Dia Nacional de Lutas\", movimento de centrais sindicais que","canonical_url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\/#article","name":"Sindicalistas prometem fechar todos os terminais de SP amanh\u00e3 | Encontra Centro SP","headline":"Sindicalistas prometem fechar todos os terminais de SP amanh\u00e3","author":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"publisher":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization"},"datePublished":"2013-07-10T13:21:56-03:00","dateModified":"2019-04-29T16:20:04-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\/#webpage"},"isPartOf":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\/#webpage"},"articleSection":"Not\u00edcias Centro SP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","name":"Not\u00edcias Centro SP"}},{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","position":2,"name":"Not\u00edcias Centro SP","item":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\/#listItem","name":"Sindicalistas prometem fechar todos os terminais de SP amanh\u00e3"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\/#listItem","position":3,"name":"Sindicalistas prometem fechar todos os terminais de SP amanh\u00e3","previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","name":"Not\u00edcias Centro SP"}}]},{"@type":"Organization","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization","name":"Encontra Centro SP","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/"},{"@type":"Person","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/","name":"Encontra Centro SP","image":{"@type":"ImageObject","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","width":96,"height":96,"caption":"Encontra Centro SP"}},{"@type":"WebPage","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\/#webpage","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\/","name":"Sindicalistas prometem fechar todos os terminais de SP amanh\u00e3 | Encontra Centro SP","description":"Os sindicalistas que bloquearam 15 terminais de \u00f4nibus nesta quarta-feira prometem fechar todos os 31 terminais da cidade a partir das 9h de amanh\u00e3. O grupo faz parte de uma chapa de oposi\u00e7\u00e3o no sindicato dos motorista e cobradores de S\u00e3o Paulo. Eles v\u00e3o aderir ao \"Dia Nacional de Lutas\", movimento de centrais sindicais que","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#website"},"breadcrumb":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\/#breadcrumblist"},"author":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"creator":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"datePublished":"2013-07-10T13:21:56-03:00","dateModified":"2019-04-29T16:20:04-03:00"},{"@type":"WebSite","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#website","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/","name":"Encontra Centro SP","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Encontra Centro SP | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","og:type":"article","og:title":"Sindicalistas prometem fechar todos os terminais de SP amanh\u00e3 | Encontra Centro SP","og:description":"Os sindicalistas que bloquearam 15 terminais de \u00f4nibus nesta quarta-feira prometem fechar todos os 31 terminais da cidade a partir das 9h de amanh\u00e3. O grupo faz parte de uma chapa de oposi\u00e7\u00e3o no sindicato dos motorista e cobradores de S\u00e3o Paulo. Eles v\u00e3o aderir ao &quot;Dia Nacional de Lutas&quot;, movimento de centrais sindicais que","og:url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\/","article:published_time":"2013-07-10T15:21:56+00:00","article:modified_time":"2019-04-29T19:20:04+00:00","twitter:card":"summary","twitter:title":"Sindicalistas prometem fechar todos os terminais de SP amanh\u00e3 | Encontra Centro SP","twitter:description":"Os sindicalistas que bloquearam 15 terminais de \u00f4nibus nesta quarta-feira prometem fechar todos os 31 terminais da cidade a partir das 9h de amanh\u00e3. O grupo faz parte de uma chapa de oposi\u00e7\u00e3o no sindicato dos motorista e cobradores de S\u00e3o Paulo. Eles v\u00e3o aderir ao &quot;Dia Nacional de Lutas&quot;, movimento de centrais sindicais que"},"aioseo_meta_data":{"post_id":"1780","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-18 18:52:10","updated":"2025-11-17 23:14:24","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/\" title=\"Not\u00edcias Centro SP\">Not\u00edcias Centro SP<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSindicalistas prometem fechar todos os terminais de SP amanh\u00e3\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre"},{"label":"Not\u00edcias Centro SP","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/"},{"label":"Sindicalistas prometem fechar todos os terminais de SP amanh\u00e3","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sindicalistas-prometem-fechar-todos-os-terminais-de-sp-amanha\/"}],"_links":{"self":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=1780"}],"version-history":[{"count":0,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1780\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=1780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=1780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=1780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}