{"id":310,"date":"2012-02-16T09:03:29","date_gmt":"2012-02-16T11:03:29","guid":{"rendered":"http:\/\/www.encontracentrosaopaulo.com.br\/noticias\/?p=310"},"modified":"2019-04-29T16:23:11","modified_gmt":"2019-04-29T19:23:11","slug":"centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira","status":"publish","type":"post","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\/","title":{"rendered":"Centro SP: Bloco formado por crian\u00e7as comemora o carnaval na pr\u00f3xima sexta-feira"},"content":{"rendered":"<div class=\"d6585b5127f45a35450431d0abc3f90c\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>A Secretaria Municipal de Cultura promove o bloco mirim das Em\u00edlias e Viscondes, da Biblioteca Monteiro Lobato, que este ano vai prestar homenagem ao personagem Pedrinho, do S\u00edtio do Picapau Amarelo. Resultado de parceria entre a biblioteca e o Instituto Espa\u00e7o Arterial, o bloco desfila pelas ruas da regi\u00e3o central reverenciando personagens da literatura de Monteiro Lobato desde 2006. Neste ano, o bloco sair\u00e1 na sexta-feira (17), \u00e0s 15h.<\/p>\n<p>Para participar da bateria n\u00e3o \u00e9 necess\u00e1rio conhecimento pr\u00e9vio nem trazer o instrumento. Os ensaios ser\u00e3o nos dias 14 e 16 de fevereiro, das 14h30 \u00e0s 17h. Para a confec\u00e7\u00e3o de fantasias e adere\u00e7os dos personagens do S\u00edtio do Picapau Amarelo, como cartolas do Visconde, perucas da Em\u00edlia, gorros do Saci, m\u00e1scaras da Cuca e aventais da Tia Nast\u00e1cia, as oficinas acontecem sempre das 15h \u00e0s 17h do dia 15 de fevereiro. Informa\u00e7\u00f5es pelos telefones 3256-4438 e 3256-4122 ou pelo site bijmlobato.blogspot.com.<\/p>\n<p><strong>Servi\u00e7o:<\/strong><br \/>\nBloco das Em\u00edlias e Viscondes<br \/>\nData: sexta-feira, 17 de fevereiro, \u00e0s 15h<br \/>\nLocal: Biblioteca Monteiro Lobato<br \/>\nEndere\u00e7o: Rua General Jardim, 485, Guia do Centro SP<\/p>\n<p><em>Fonte: Prefeitura de S. Paulo<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A Secretaria Municipal de Cultura promove o bloco mirim das Em\u00edlias e Viscondes, da Biblioteca Monteiro Lobato, que este ano vai prestar homenagem ao personagem Pedrinho, do S\u00edtio do Picapau Amarelo. Resultado de parceria entre a biblioteca e o Instituto Espa\u00e7o Arterial, o bloco desfila pelas ruas da regi\u00e3o central reverenciando personagens da literatura de Monteiro Lobato desde 2006. Neste ano, o bloco sair\u00e1 na sexta-feira (17), \u00e0s 15h. Para participar da bateria n\u00e3o \u00e9 necess\u00e1rio conhecimento pr\u00e9vio nem trazer o instrumento. Os ensaios ser\u00e3o nos dias 14 e 16 de fevereiro, das 14h30 \u00e0s 17h. Para a confec\u00e7\u00e3o de <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-310","post","type-post","status-publish","format-standard","hentry","category-noticias-no-centro-sp"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"A Secretaria Municipal de Cultura promove o bloco mirim das Em\u00edlias e Viscondes, da Biblioteca Monteiro Lobato, que este ano vai prestar homenagem ao personagem Pedrinho, do S\u00edtio do Picapau Amarelo. Resultado de parceria entre a biblioteca e o Instituto Espa\u00e7o Arterial, o bloco desfila pelas ruas da regi\u00e3o central reverenciando personagens da literatura de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Encontra Centro SP\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Encontra Centro SP | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Centro SP: Bloco formado por crian\u00e7as comemora o carnaval na pr\u00f3xima sexta-feira | Encontra Centro SP\" \/>\n\t\t<meta property=\"og:description\" content=\"A Secretaria Municipal de Cultura promove o bloco mirim das Em\u00edlias e Viscondes, da Biblioteca Monteiro Lobato, que este ano vai prestar homenagem ao personagem Pedrinho, do S\u00edtio do Picapau Amarelo. Resultado de parceria entre a biblioteca e o Instituto Espa\u00e7o Arterial, o bloco desfila pelas ruas da regi\u00e3o central reverenciando personagens da literatura de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-02-16T11:03:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-29T19:23:11+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Centro SP: Bloco formado por crian\u00e7as comemora o carnaval na pr\u00f3xima sexta-feira | Encontra Centro SP\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A Secretaria Municipal de Cultura promove o bloco mirim das Em\u00edlias e Viscondes, da Biblioteca Monteiro Lobato, que este ano vai prestar homenagem ao personagem Pedrinho, do S\u00edtio do Picapau Amarelo. Resultado de parceria entre a biblioteca e o Instituto Espa\u00e7o Arterial, o bloco desfila pelas ruas da regi\u00e3o central reverenciando personagens da literatura de\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\\\/#article\",\"name\":\"Centro SP: Bloco formado por crian\\u00e7as comemora o carnaval na pr\\u00f3xima sexta-feira | Encontra Centro SP\",\"headline\":\"Centro SP: Bloco formado por crian\\u00e7as comemora o carnaval na pr\\u00f3xima sexta-feira\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\"},\"datePublished\":\"2012-02-16T09:03:29-02:00\",\"dateModified\":\"2019-04-29T16:23:11-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias Centro SP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"name\":\"Not\\u00edcias Centro SP\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias Centro SP\",\"item\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\\\/#listItem\",\"name\":\"Centro SP: Bloco formado por crian\\u00e7as comemora o carnaval na pr\\u00f3xima sexta-feira\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\\\/#listItem\",\"position\":3,\"name\":\"Centro SP: Bloco formado por crian\\u00e7as comemora o carnaval na pr\\u00f3xima sexta-feira\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"name\":\"Not\\u00edcias Centro SP\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\",\"name\":\"Encontra Centro SP\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Centro SP e regi\\u00e3o.\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/\",\"name\":\"Encontra Centro SP\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Encontra Centro SP\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\\\/#webpage\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\\\/\",\"name\":\"Centro SP: Bloco formado por crian\\u00e7as comemora o carnaval na pr\\u00f3xima sexta-feira | Encontra Centro SP\",\"description\":\"A Secretaria Municipal de Cultura promove o bloco mirim das Em\\u00edlias e Viscondes, da Biblioteca Monteiro Lobato, que este ano vai prestar homenagem ao personagem Pedrinho, do S\\u00edtio do Picapau Amarelo. Resultado de parceria entre a biblioteca e o Instituto Espa\\u00e7o Arterial, o bloco desfila pelas ruas da regi\\u00e3o central reverenciando personagens da literatura de\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"datePublished\":\"2012-02-16T09:03:29-02:00\",\"dateModified\":\"2019-04-29T16:23:11-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/\",\"name\":\"Encontra Centro SP\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Centro SP e regi\\u00e3o.\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Centro SP: Bloco formado por crian\u00e7as comemora o carnaval na pr\u00f3xima sexta-feira | Encontra Centro SP","description":"A Secretaria Municipal de Cultura promove o bloco mirim das Em\u00edlias e Viscondes, da Biblioteca Monteiro Lobato, que este ano vai prestar homenagem ao personagem Pedrinho, do S\u00edtio do Picapau Amarelo. Resultado de parceria entre a biblioteca e o Instituto Espa\u00e7o Arterial, o bloco desfila pelas ruas da regi\u00e3o central reverenciando personagens da literatura de","canonical_url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\/#article","name":"Centro SP: Bloco formado por crian\u00e7as comemora o carnaval na pr\u00f3xima sexta-feira | Encontra Centro SP","headline":"Centro SP: Bloco formado por crian\u00e7as comemora o carnaval na pr\u00f3xima sexta-feira","author":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"publisher":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization"},"datePublished":"2012-02-16T09:03:29-02:00","dateModified":"2019-04-29T16:23:11-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\/#webpage"},"isPartOf":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\/#webpage"},"articleSection":"Not\u00edcias Centro SP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","name":"Not\u00edcias Centro SP"}},{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","position":2,"name":"Not\u00edcias Centro SP","item":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\/#listItem","name":"Centro SP: Bloco formado por crian\u00e7as comemora o carnaval na pr\u00f3xima sexta-feira"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\/#listItem","position":3,"name":"Centro SP: Bloco formado por crian\u00e7as comemora o carnaval na pr\u00f3xima sexta-feira","previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","name":"Not\u00edcias Centro SP"}}]},{"@type":"Organization","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization","name":"Encontra Centro SP","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/"},{"@type":"Person","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/","name":"Encontra Centro SP","image":{"@type":"ImageObject","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","width":96,"height":96,"caption":"Encontra Centro SP"}},{"@type":"WebPage","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\/#webpage","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\/","name":"Centro SP: Bloco formado por crian\u00e7as comemora o carnaval na pr\u00f3xima sexta-feira | Encontra Centro SP","description":"A Secretaria Municipal de Cultura promove o bloco mirim das Em\u00edlias e Viscondes, da Biblioteca Monteiro Lobato, que este ano vai prestar homenagem ao personagem Pedrinho, do S\u00edtio do Picapau Amarelo. Resultado de parceria entre a biblioteca e o Instituto Espa\u00e7o Arterial, o bloco desfila pelas ruas da regi\u00e3o central reverenciando personagens da literatura de","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#website"},"breadcrumb":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\/#breadcrumblist"},"author":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"creator":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"datePublished":"2012-02-16T09:03:29-02:00","dateModified":"2019-04-29T16:23:11-03:00"},{"@type":"WebSite","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#website","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/","name":"Encontra Centro SP","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Encontra Centro SP | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","og:type":"article","og:title":"Centro SP: Bloco formado por crian\u00e7as comemora o carnaval na pr\u00f3xima sexta-feira | Encontra Centro SP","og:description":"A Secretaria Municipal de Cultura promove o bloco mirim das Em\u00edlias e Viscondes, da Biblioteca Monteiro Lobato, que este ano vai prestar homenagem ao personagem Pedrinho, do S\u00edtio do Picapau Amarelo. Resultado de parceria entre a biblioteca e o Instituto Espa\u00e7o Arterial, o bloco desfila pelas ruas da regi\u00e3o central reverenciando personagens da literatura de","og:url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\/","article:published_time":"2012-02-16T11:03:29+00:00","article:modified_time":"2019-04-29T19:23:11+00:00","twitter:card":"summary","twitter:title":"Centro SP: Bloco formado por crian\u00e7as comemora o carnaval na pr\u00f3xima sexta-feira | Encontra Centro SP","twitter:description":"A Secretaria Municipal de Cultura promove o bloco mirim das Em\u00edlias e Viscondes, da Biblioteca Monteiro Lobato, que este ano vai prestar homenagem ao personagem Pedrinho, do S\u00edtio do Picapau Amarelo. Resultado de parceria entre a biblioteca e o Instituto Espa\u00e7o Arterial, o bloco desfila pelas ruas da regi\u00e3o central reverenciando personagens da literatura de"},"aioseo_meta_data":{"post_id":"310","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-18 18:52:11","updated":"2025-11-13 14:58:29","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/\" title=\"Not\u00edcias Centro SP\">Not\u00edcias Centro SP<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCentro SP: Bloco formado por crian\u00e7as comemora o carnaval na pr\u00f3xima sexta-feira\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre"},{"label":"Not\u00edcias Centro SP","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/"},{"label":"Centro SP: Bloco formado por crian\u00e7as comemora o carnaval na pr\u00f3xima sexta-feira","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/centro-sp-bloco-formado-por-criancas-comemora-o-carnaval-na-proxima-sexta-feira\/"}],"_links":{"self":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=310"}],"version-history":[{"count":0,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/310\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}