{"id":657,"date":"2012-05-31T08:20:25","date_gmt":"2012-05-31T10:20:25","guid":{"rendered":"http:\/\/www.encontracentrosaopaulo.com.br\/noticias\/?p=657"},"modified":"2019-04-29T16:23:04","modified_gmt":"2019-04-29T19:23:04","slug":"termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros","status":"publish","type":"post","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\/","title":{"rendered":"Termina hoje no Centro exposi\u00e7\u00e3o que traz sequ\u00eancia de fotografias em livros"},"content":{"rendered":"<div class=\"d6585b5127f45a35450431d0abc3f90c\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>As artistas J\u00falia Giannetti e Simone Quintino de Lima contru\u00edram uma s\u00e9rie de<em> flip books<\/em>, livreto com uma sequ\u00eancia de fotografias, que ao ser folheado, passa a impress\u00e3o de movimento. <em>Flip book<\/em> \u00e9 um termo ingl\u00eas tamb\u00e9m conhecido como cinema de bolso.<\/p>\n<p>O resultado do trabalho est\u00e1 na exposi\u00e7\u00e3o <em>Ef\u00eamero Frame<\/em>, que est\u00e1 em cartaz na Biblioteca Infantojuvenil Monteiro Lobato at\u00e9 hoje (31). Os <em>flip books<\/em> da mostra foram feitos para ocupar os espa\u00e7os da biblioteca de forma  acess\u00edvel, para que as crian\u00e7as possam manipul\u00e1-los ao visitar o local.  Al\u00e9m dos livretos, um livro de anima\u00e7\u00e3o completa a mostra.<\/p>\n<p><strong>Servi\u00e7o:<\/strong><\/p>\n<p><strong>Evento<\/strong><em>: Ef\u00eamero Frame<\/em><br \/>\n<strong>Data: <\/strong>at\u00e9 31 de maio<br \/>\n<strong>Hor\u00e1rio:<\/strong> de segunda a sexta-feira, das 8 \u00e0s 18 horas<br \/>\n<strong>Local: <\/strong><a title=\"Biblioteca Monteiro Lobato\" href=\"http:\/\/www.encontracentrosaopaulo.com.br\/centro-sp\/biblioteca-monteiro-lobato-no-centro-sp.shtml\" target=\"_blank\">Biblioteca Monteiro Lobato<\/a><br \/>\n<strong>Endere\u00e7o: <\/strong>rua General Jardim, 485 \u2013 Consola\u00e7\u00e3o<br \/>\n<strong>Entrada Gratuita<\/strong><\/p>\n<p><strong> <\/strong><\/p>\n<p><strong> <\/strong><em>Fonte: Prefeitura de S. Paulo<\/em><strong><br \/>\n<\/strong><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>As artistas J\u00falia Giannetti e Simone Quintino de Lima contru\u00edram uma s\u00e9rie de flip books, livreto com uma sequ\u00eancia de fotografias, que ao ser folheado, passa a impress\u00e3o de movimento. Flip book \u00e9 um termo ingl\u00eas tamb\u00e9m conhecido como cinema de bolso. O resultado do trabalho est\u00e1 na exposi\u00e7\u00e3o Ef\u00eamero Frame, que est\u00e1 em cartaz na Biblioteca Infantojuvenil Monteiro Lobato at\u00e9 hoje (31). Os flip books da mostra foram feitos para ocupar os espa\u00e7os da biblioteca de forma acess\u00edvel, para que as crian\u00e7as possam manipul\u00e1-los ao visitar o local. Al\u00e9m dos livretos, um livro de anima\u00e7\u00e3o completa a mostra. Servi\u00e7o: <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-657","post","type-post","status-publish","format-standard","hentry","category-noticias-no-centro-sp"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"As artistas J\u00falia Giannetti e Simone Quintino de Lima contru\u00edram uma s\u00e9rie de flip books, livreto com uma sequ\u00eancia de fotografias, que ao ser folheado, passa a impress\u00e3o de movimento. Flip book \u00e9 um termo ingl\u00eas tamb\u00e9m conhecido como cinema de bolso. O resultado do trabalho est\u00e1 na exposi\u00e7\u00e3o Ef\u00eamero Frame, que est\u00e1 em cartaz\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Encontra Centro SP\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Encontra Centro SP | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Termina hoje no Centro exposi\u00e7\u00e3o que traz sequ\u00eancia de fotografias em livros | Encontra Centro SP\" \/>\n\t\t<meta property=\"og:description\" content=\"As artistas J\u00falia Giannetti e Simone Quintino de Lima contru\u00edram uma s\u00e9rie de flip books, livreto com uma sequ\u00eancia de fotografias, que ao ser folheado, passa a impress\u00e3o de movimento. Flip book \u00e9 um termo ingl\u00eas tamb\u00e9m conhecido como cinema de bolso. O resultado do trabalho est\u00e1 na exposi\u00e7\u00e3o Ef\u00eamero Frame, que est\u00e1 em cartaz\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-05-31T10:20:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-29T19:23:04+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Termina hoje no Centro exposi\u00e7\u00e3o que traz sequ\u00eancia de fotografias em livros | Encontra Centro SP\" \/>\n\t\t<meta name=\"twitter:description\" content=\"As artistas J\u00falia Giannetti e Simone Quintino de Lima contru\u00edram uma s\u00e9rie de flip books, livreto com uma sequ\u00eancia de fotografias, que ao ser folheado, passa a impress\u00e3o de movimento. Flip book \u00e9 um termo ingl\u00eas tamb\u00e9m conhecido como cinema de bolso. O resultado do trabalho est\u00e1 na exposi\u00e7\u00e3o Ef\u00eamero Frame, que est\u00e1 em cartaz\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\\\/#article\",\"name\":\"Termina hoje no Centro exposi\\u00e7\\u00e3o que traz sequ\\u00eancia de fotografias em livros | Encontra Centro SP\",\"headline\":\"Termina hoje no Centro exposi\\u00e7\\u00e3o que traz sequ\\u00eancia de fotografias em livros\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\"},\"datePublished\":\"2012-05-31T08:20:25-03:00\",\"dateModified\":\"2019-04-29T16:23:04-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias Centro SP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"name\":\"Not\\u00edcias Centro SP\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias Centro SP\",\"item\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\\\/#listItem\",\"name\":\"Termina hoje no Centro exposi\\u00e7\\u00e3o que traz sequ\\u00eancia de fotografias em livros\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\\\/#listItem\",\"position\":3,\"name\":\"Termina hoje no Centro exposi\\u00e7\\u00e3o que traz sequ\\u00eancia de fotografias em livros\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"name\":\"Not\\u00edcias Centro SP\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\",\"name\":\"Encontra Centro SP\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Centro SP e regi\\u00e3o.\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/\",\"name\":\"Encontra Centro SP\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Encontra Centro SP\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\\\/#webpage\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\\\/\",\"name\":\"Termina hoje no Centro exposi\\u00e7\\u00e3o que traz sequ\\u00eancia de fotografias em livros | Encontra Centro SP\",\"description\":\"As artistas J\\u00falia Giannetti e Simone Quintino de Lima contru\\u00edram uma s\\u00e9rie de flip books, livreto com uma sequ\\u00eancia de fotografias, que ao ser folheado, passa a impress\\u00e3o de movimento. Flip book \\u00e9 um termo ingl\\u00eas tamb\\u00e9m conhecido como cinema de bolso. O resultado do trabalho est\\u00e1 na exposi\\u00e7\\u00e3o Ef\\u00eamero Frame, que est\\u00e1 em cartaz\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"datePublished\":\"2012-05-31T08:20:25-03:00\",\"dateModified\":\"2019-04-29T16:23:04-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/\",\"name\":\"Encontra Centro SP\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Centro SP e regi\\u00e3o.\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Termina hoje no Centro exposi\u00e7\u00e3o que traz sequ\u00eancia de fotografias em livros | Encontra Centro SP","description":"As artistas J\u00falia Giannetti e Simone Quintino de Lima contru\u00edram uma s\u00e9rie de flip books, livreto com uma sequ\u00eancia de fotografias, que ao ser folheado, passa a impress\u00e3o de movimento. Flip book \u00e9 um termo ingl\u00eas tamb\u00e9m conhecido como cinema de bolso. O resultado do trabalho est\u00e1 na exposi\u00e7\u00e3o Ef\u00eamero Frame, que est\u00e1 em cartaz","canonical_url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\/#article","name":"Termina hoje no Centro exposi\u00e7\u00e3o que traz sequ\u00eancia de fotografias em livros | Encontra Centro SP","headline":"Termina hoje no Centro exposi\u00e7\u00e3o que traz sequ\u00eancia de fotografias em livros","author":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"publisher":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization"},"datePublished":"2012-05-31T08:20:25-03:00","dateModified":"2019-04-29T16:23:04-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\/#webpage"},"isPartOf":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\/#webpage"},"articleSection":"Not\u00edcias Centro SP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","name":"Not\u00edcias Centro SP"}},{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","position":2,"name":"Not\u00edcias Centro SP","item":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\/#listItem","name":"Termina hoje no Centro exposi\u00e7\u00e3o que traz sequ\u00eancia de fotografias em livros"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\/#listItem","position":3,"name":"Termina hoje no Centro exposi\u00e7\u00e3o que traz sequ\u00eancia de fotografias em livros","previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","name":"Not\u00edcias Centro SP"}}]},{"@type":"Organization","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization","name":"Encontra Centro SP","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/"},{"@type":"Person","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/","name":"Encontra Centro SP","image":{"@type":"ImageObject","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","width":96,"height":96,"caption":"Encontra Centro SP"}},{"@type":"WebPage","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\/#webpage","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\/","name":"Termina hoje no Centro exposi\u00e7\u00e3o que traz sequ\u00eancia de fotografias em livros | Encontra Centro SP","description":"As artistas J\u00falia Giannetti e Simone Quintino de Lima contru\u00edram uma s\u00e9rie de flip books, livreto com uma sequ\u00eancia de fotografias, que ao ser folheado, passa a impress\u00e3o de movimento. Flip book \u00e9 um termo ingl\u00eas tamb\u00e9m conhecido como cinema de bolso. O resultado do trabalho est\u00e1 na exposi\u00e7\u00e3o Ef\u00eamero Frame, que est\u00e1 em cartaz","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#website"},"breadcrumb":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\/#breadcrumblist"},"author":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"creator":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"datePublished":"2012-05-31T08:20:25-03:00","dateModified":"2019-04-29T16:23:04-03:00"},{"@type":"WebSite","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#website","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/","name":"Encontra Centro SP","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Encontra Centro SP | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","og:type":"article","og:title":"Termina hoje no Centro exposi\u00e7\u00e3o que traz sequ\u00eancia de fotografias em livros | Encontra Centro SP","og:description":"As artistas J\u00falia Giannetti e Simone Quintino de Lima contru\u00edram uma s\u00e9rie de flip books, livreto com uma sequ\u00eancia de fotografias, que ao ser folheado, passa a impress\u00e3o de movimento. Flip book \u00e9 um termo ingl\u00eas tamb\u00e9m conhecido como cinema de bolso. O resultado do trabalho est\u00e1 na exposi\u00e7\u00e3o Ef\u00eamero Frame, que est\u00e1 em cartaz","og:url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\/","article:published_time":"2012-05-31T10:20:25+00:00","article:modified_time":"2019-04-29T19:23:04+00:00","twitter:card":"summary","twitter:title":"Termina hoje no Centro exposi\u00e7\u00e3o que traz sequ\u00eancia de fotografias em livros | Encontra Centro SP","twitter:description":"As artistas J\u00falia Giannetti e Simone Quintino de Lima contru\u00edram uma s\u00e9rie de flip books, livreto com uma sequ\u00eancia de fotografias, que ao ser folheado, passa a impress\u00e3o de movimento. Flip book \u00e9 um termo ingl\u00eas tamb\u00e9m conhecido como cinema de bolso. O resultado do trabalho est\u00e1 na exposi\u00e7\u00e3o Ef\u00eamero Frame, que est\u00e1 em cartaz"},"aioseo_meta_data":{"post_id":"657","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-20 23:28:59","updated":"2025-11-14 07:04:54","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/\" title=\"Not\u00edcias Centro SP\">Not\u00edcias Centro SP<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTermina hoje no Centro exposi\u00e7\u00e3o que traz sequ\u00eancia de fotografias em livros\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre"},{"label":"Not\u00edcias Centro SP","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/"},{"label":"Termina hoje no Centro exposi\u00e7\u00e3o que traz sequ\u00eancia de fotografias em livros","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/termina-hoje-no-centro-exposicao-que-tras-sequencia-de-fotos-em-livros\/"}],"_links":{"self":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=657"}],"version-history":[{"count":0,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/657\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}