{"id":6888,"date":"2026-07-14T16:39:47","date_gmt":"2026-07-14T19:39:47","guid":{"rendered":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/"},"modified":"2026-07-14T16:39:47","modified_gmt":"2026-07-14T19:39:47","slug":"sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos","status":"publish","type":"post","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/","title":{"rendered":"Sesc S\u00e3o Paulo abre primeira turma do programa de Educa\u00e7\u00e3o para Jovens e Adultos"},"content":{"rendered":"<div class=\"d6585b5127f45a35450431d0abc3f90c\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<h2>O que \u00e9 o Sesc EAD EJA?<\/h2>\n<p>O <strong>Sesc EAD EJA<\/strong> \u00e9 um programa que visa proporcionar a possibilidade de forma\u00e7\u00e3o gratuita para jovens e adultos que desejam concluir o Ensino M\u00e9dio. Atrav\u00e9s deste projeto, a institui\u00e7\u00e3o oferece a oportunidade de obter uma qualifica\u00e7\u00e3o profissional ao mesmo tempo, permitindo o acesso \u00e0 educa\u00e7\u00e3o b\u00e1sica e ao mesmo tempo preparando os alunos para o mercado de trabalho.<\/p>\n<h2>Detalhes sobre o curso<\/h2>\n<p>O curso do Sesc EAD EJA \u00e9 estruturado para ocorrer ao longo de <strong>tr\u00eas semestres<\/strong>, totalizando uma carga hor\u00e1ria de <strong>1.200 horas<\/strong>. Este formato possibilita que metade das aulas sejam realizadas de forma virtual, enquanto a outra metade acontece presencialmente, garantindo flexibilidade e adaptabilidade \u00e0s necessidades dos alunos.<\/p>\n<h2>Formato h\u00edbrido: online e presencial<\/h2>\n<p>O Sesc EAD EJA adota um <strong>modelo h\u00edbrido<\/strong>, combinando aulas online e presenciais. As aulas presenciais s\u00e3o ministradas na <strong>unidade S\u00e3o Bento<\/strong>, situada no centro de S\u00e3o Paulo. Este sistema h\u00edbrido \u00e9 projetado para atender diferentes estilos de aprendizagem, tornando a forma\u00e7\u00e3o acess\u00edvel e eficaz.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-content\/uploads\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos.webp\" alt=\"Educa\u00e7\u00e3o para Jovens e Adultos\" loading=\"lazy\" \/><\/p>\n<h2>Vagas e inscri\u00e7\u00f5es abertas<\/h2>\n<p>Nesta nova turma, <strong>30 vagas<\/strong> estar\u00e3o dispon\u00edveis, focadas em alunos que buscam a qualifica\u00e7\u00e3o em <strong>Produ\u00e7\u00e3o Cultural<\/strong>. As inscri\u00e7\u00f5es podem ser realizadas a partir do dia <strong>15 de junho<\/strong> no site oficial <a href=\"https:\/\/www.sesc.com.br\/ead\">www.sesc.com.br\/ead<\/a>.<\/p>\n<h2>Qualifica\u00e7\u00e3o profissional em Produ\u00e7\u00e3o Cultural<\/h2>\n<p>Al\u00e9m de concluir o ensino m\u00e9dio, os participantes do Sesc EAD EJA ter\u00e3o acesso \u00e0 forma\u00e7\u00e3o em <strong>Produ\u00e7\u00e3o Cultural<\/strong>. Esse componente proporciona aos alunos conhecimentos valiosos que s\u00e3o altamente relevantes no mundo profissional atual, preparando-os para atuar em diversos setores dentro da \u00e1rea cultural.<\/p>\n<h2>Crit\u00e9rios de sele\u00e7\u00e3o dos candidatos<\/h2>\n<p>A sele\u00e7\u00e3o dos candidatos ser\u00e1 regida por um edital que especifica os crit\u00e9rios e requisitos. O Sesc adota crit\u00e9rios baseados no <strong>Pacto Nacional pela Supera\u00e7\u00e3o do Analfabetismo<\/strong> e prioriza a inclus\u00e3o de grupos sociais que se encontram em situa\u00e7\u00f5es de vulnerabilidade. Isso inclui uma an\u00e1lise das condi\u00e7\u00f5es socioecon\u00f4micas, \u00e9tnico-raciais e de g\u00eanero dos inscritos.<\/p>\n<h2>Impacto do Sesc EAD EJA na educa\u00e7\u00e3o brasileira<\/h2>\n<p>Desde seu lan\u00e7amento, o Sesc EAD EJA j\u00e1 impactou a vida de mais de <strong>7 mil estudantes<\/strong> em todo o Brasil. Com essa abordagem mais flex\u00edvel, o programa se firmou como uma alternativa vi\u00e1vel para aqueles que n\u00e3o conseguiram completar o Ensino M\u00e9dio em idade regular, contribuindo assim para a redu\u00e7\u00e3o da evas\u00e3o escolar e promovendo a inclus\u00e3o educacional.<\/p>\n<h2>Hist\u00f3rias de sucesso de alunos formados<\/h2>\n<p>Os alunos que completam o curso do Sesc EAD EJA frequentemente compartilham suas hist\u00f3rias de transforma\u00e7\u00e3o e sucesso. Muitos deles conseguiram iniciar novas carreiras, aprimorar suas habilidades ou at\u00e9 mesmo prosseguir com estudos superiores, levando suas vidas e suas fam\u00edlias a novas oportunidades. Essas experi\u00eancias demonstram o valor e a import\u00e2ncia da educa\u00e7\u00e3o na realiza\u00e7\u00e3o pessoal e profissional.<\/p>\n<h2>Como se inscrever no programa<\/h2>\n<p>Para se inscrever no Sesc EAD EJA, os interessados devem acessar o site <a href=\"https:\/\/www.sesc.com.br\/ead\">www.sesc.com.br\/ead<\/a> e seguir os passos indicados no processo seletivo. \u00c9 importante que os candidatos atendam aos requisitos b\u00e1sicos, que incluem ter pelo menos <strong>18 anos<\/strong> e o Ensino Fundamental completo, al\u00e9m da renda familiar per capita n\u00e3o ultrapassar dois sal\u00e1rios m\u00ednimos.<\/p>\n<h2>Benef\u00edcios de se qualificar atrav\u00e9s do Sesc<\/h2>\n<p>A qualifica\u00e7\u00e3o atrav\u00e9s do Sesc oferece diversas vantagens, como a possibilidade de concluir a educa\u00e7\u00e3o b\u00e1sica, adquirir habilidades em uma \u00e1rea de atua\u00e7\u00e3o demandada no mercado, al\u00e9m de criar redes de contato com outros alunos e profissionais. O acesso a cursos gratuitos de qualidade tamb\u00e9m representa uma oportunidade de transforma\u00e7\u00e3o social e econ\u00f4mica significativa para os participantes.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Educa\u00e7\u00e3o para jovens e adultos com forma\u00e7\u00e3o gratuita no Sesc S\u00e3o Paulo. Descubra como se inscrever!<\/p>\n","protected":false},"author":1,"featured_media":6887,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-6888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao-no-centro-sp","has_thumb"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Educa\u00e7\u00e3o para jovens e adultos com forma\u00e7\u00e3o gratuita no Sesc S\u00e3o Paulo. Descubra como se inscrever!\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Encontra Centro SP\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Encontra Centro SP | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sesc S\u00e3o Paulo abre primeira turma do programa de Educa\u00e7\u00e3o para Jovens e Adultos | Encontra Centro SP\" \/>\n\t\t<meta property=\"og:description\" content=\"Educa\u00e7\u00e3o para jovens e adultos com forma\u00e7\u00e3o gratuita no Sesc S\u00e3o Paulo. Descubra como se inscrever!\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-14T19:39:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-14T19:39:47+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sesc S\u00e3o Paulo abre primeira turma do programa de Educa\u00e7\u00e3o para Jovens e Adultos | Encontra Centro SP\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Educa\u00e7\u00e3o para jovens e adultos com forma\u00e7\u00e3o gratuita no Sesc S\u00e3o Paulo. Descubra como se inscrever!\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\\\/#article\",\"name\":\"Sesc S\\u00e3o Paulo abre primeira turma do programa de Educa\\u00e7\\u00e3o para Jovens e Adultos | Encontra Centro SP\",\"headline\":\"Sesc S\\u00e3o Paulo abre primeira turma do programa de Educa\\u00e7\\u00e3o para Jovens e Adultos\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos.webp\",\"width\":280,\"height\":280,\"caption\":\"Educa\\u00e7\\u00e3o para Jovens e Adultos\"},\"datePublished\":\"2026-07-14T16:39:47-03:00\",\"dateModified\":\"2026-07-14T16:39:47-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\\\/#webpage\"},\"articleSection\":\"Educa\\u00e7\\u00e3o Centro SP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/educacao-no-centro-sp\\\/#listItem\",\"name\":\"Educa\\u00e7\\u00e3o Centro SP\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/educacao-no-centro-sp\\\/#listItem\",\"position\":2,\"name\":\"Educa\\u00e7\\u00e3o Centro SP\",\"item\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/educacao-no-centro-sp\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\\\/#listItem\",\"name\":\"Sesc S\\u00e3o Paulo abre primeira turma do programa de Educa\\u00e7\\u00e3o para Jovens e Adultos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\\\/#listItem\",\"position\":3,\"name\":\"Sesc S\\u00e3o Paulo abre primeira turma do programa de Educa\\u00e7\\u00e3o para Jovens e Adultos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/educacao-no-centro-sp\\\/#listItem\",\"name\":\"Educa\\u00e7\\u00e3o Centro SP\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\",\"name\":\"Encontra Centro SP\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Centro SP e regi\\u00e3o.\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/\",\"name\":\"Encontra Centro SP\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Encontra Centro SP\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\\\/#webpage\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\\\/\",\"name\":\"Sesc S\\u00e3o Paulo abre primeira turma do programa de Educa\\u00e7\\u00e3o para Jovens e Adultos | Encontra Centro SP\",\"description\":\"Educa\\u00e7\\u00e3o para jovens e adultos com forma\\u00e7\\u00e3o gratuita no Sesc S\\u00e3o Paulo. Descubra como se inscrever!\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos.webp\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\\\/#mainImage\",\"width\":280,\"height\":280,\"caption\":\"Educa\\u00e7\\u00e3o para Jovens e Adultos\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\\\/#mainImage\"},\"datePublished\":\"2026-07-14T16:39:47-03:00\",\"dateModified\":\"2026-07-14T16:39:47-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/\",\"name\":\"Encontra Centro SP\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Centro SP e regi\\u00e3o.\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sesc S\u00e3o Paulo abre primeira turma do programa de Educa\u00e7\u00e3o para Jovens e Adultos | Encontra Centro SP","description":"Educa\u00e7\u00e3o para jovens e adultos com forma\u00e7\u00e3o gratuita no Sesc S\u00e3o Paulo. Descubra como se inscrever!","canonical_url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/#article","name":"Sesc S\u00e3o Paulo abre primeira turma do programa de Educa\u00e7\u00e3o para Jovens e Adultos | Encontra Centro SP","headline":"Sesc S\u00e3o Paulo abre primeira turma do programa de Educa\u00e7\u00e3o para Jovens e Adultos","author":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"publisher":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-content\/uploads\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos.webp","width":280,"height":280,"caption":"Educa\u00e7\u00e3o para Jovens e Adultos"},"datePublished":"2026-07-14T16:39:47-03:00","dateModified":"2026-07-14T16:39:47-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/#webpage"},"isPartOf":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/#webpage"},"articleSection":"Educa\u00e7\u00e3o Centro SP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/educacao-no-centro-sp\/#listItem","name":"Educa\u00e7\u00e3o Centro SP"}},{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/educacao-no-centro-sp\/#listItem","position":2,"name":"Educa\u00e7\u00e3o Centro SP","item":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/educacao-no-centro-sp\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/#listItem","name":"Sesc S\u00e3o Paulo abre primeira turma do programa de Educa\u00e7\u00e3o para Jovens e Adultos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/#listItem","position":3,"name":"Sesc S\u00e3o Paulo abre primeira turma do programa de Educa\u00e7\u00e3o para Jovens e Adultos","previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/educacao-no-centro-sp\/#listItem","name":"Educa\u00e7\u00e3o Centro SP"}}]},{"@type":"Organization","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization","name":"Encontra Centro SP","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/"},{"@type":"Person","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/","name":"Encontra Centro SP","image":{"@type":"ImageObject","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","width":96,"height":96,"caption":"Encontra Centro SP"}},{"@type":"WebPage","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/#webpage","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/","name":"Sesc S\u00e3o Paulo abre primeira turma do programa de Educa\u00e7\u00e3o para Jovens e Adultos | Encontra Centro SP","description":"Educa\u00e7\u00e3o para jovens e adultos com forma\u00e7\u00e3o gratuita no Sesc S\u00e3o Paulo. Descubra como se inscrever!","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#website"},"breadcrumb":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/#breadcrumblist"},"author":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"creator":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-content\/uploads\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos.webp","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/#mainImage","width":280,"height":280,"caption":"Educa\u00e7\u00e3o para Jovens e Adultos"},"primaryImageOfPage":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/#mainImage"},"datePublished":"2026-07-14T16:39:47-03:00","dateModified":"2026-07-14T16:39:47-03:00"},{"@type":"WebSite","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#website","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/","name":"Encontra Centro SP","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Encontra Centro SP | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","og:type":"article","og:title":"Sesc S\u00e3o Paulo abre primeira turma do programa de Educa\u00e7\u00e3o para Jovens e Adultos | Encontra Centro SP","og:description":"Educa\u00e7\u00e3o para jovens e adultos com forma\u00e7\u00e3o gratuita no Sesc S\u00e3o Paulo. Descubra como se inscrever!","og:url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/","article:published_time":"2026-07-14T19:39:47+00:00","article:modified_time":"2026-07-14T19:39:47+00:00","twitter:card":"summary","twitter:title":"Sesc S\u00e3o Paulo abre primeira turma do programa de Educa\u00e7\u00e3o para Jovens e Adultos | Encontra Centro SP","twitter:description":"Educa\u00e7\u00e3o para jovens e adultos com forma\u00e7\u00e3o gratuita no Sesc S\u00e3o Paulo. Descubra como se inscrever!"},"aioseo_meta_data":{"post_id":"6888","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-07-14 19:39:47","updated":"2026-07-14 20:08:04","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/educacao-no-centro-sp\/\" title=\"Educa\u00e7\u00e3o Centro SP\">Educa\u00e7\u00e3o Centro SP<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSesc S\u00e3o Paulo abre primeira turma do programa de Educa\u00e7\u00e3o para Jovens e Adultos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre"},{"label":"Educa\u00e7\u00e3o Centro SP","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/educacao-no-centro-sp\/"},{"label":"Sesc S\u00e3o Paulo abre primeira turma do programa de Educa\u00e7\u00e3o para Jovens e Adultos","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sesc-sao-paulo-abre-primeira-turma-do-programa-de-educacao-para-jovens-e-adultos\/"}],"_links":{"self":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/6888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=6888"}],"version-history":[{"count":0,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/6888\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/media\/6887"}],"wp:attachment":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=6888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=6888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=6888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}