{"id":835,"date":"2012-08-02T09:43:14","date_gmt":"2012-08-02T11:43:14","guid":{"rendered":"http:\/\/www.encontracentrosaopaulo.com.br\/noticias\/?p=835"},"modified":"2019-04-29T16:22:25","modified_gmt":"2019-04-29T19:22:25","slug":"sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro","status":"publish","type":"post","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\/","title":{"rendered":"S\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro"},"content":{"rendered":"<div class=\"d6585b5127f45a35450431d0abc3f90c\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Come\u00e7am na pr\u00f3xima segunda-feira (6\/8), as inscri\u00e7\u00f5es para novas  turmas do Curso B\u00e1sico de Empreendedorismo, da Academia de Microfinan\u00e7as  do banco de microcr\u00e9dito do S\u00e3o Paulo Confia, da Secretaria Municipal  de Desenvolvimento Econ\u00f4mico e do Trabalho.<\/p>\n<p>S\u00e3o 3 mil vagas, com  12h de curso, divididas em 4 encontros de tr\u00eas horas cada. No per\u00edodo  matutino, as aulas v\u00e3o das 9h ao meio-dia e no vespertino das 14h \u00e0s  17h. O curso \u00e9 gratuito e est\u00e1 aberto para todos que tiverem interesse  em participar e, ao final, os participantes recebem um certificado.<\/p>\n<p>Durante  as aulas, os participantes aprendem como controlar o dinheiro, t\u00e9cnicas  de vendas, forma\u00e7\u00e3o de pre\u00e7o, no\u00e7\u00f5es b\u00e1sicas de marketing, dicas de  como comprar mais barato, dentre outros temas que contribuem para  amplia\u00e7\u00e3o e manuten\u00e7\u00e3o dos neg\u00f3cios.<\/p>\n<p>Os cursos acontecem em  Santana, Brasil\u00e2ndia, Butant\u00e3, Centro, Vila Prudente, Itaim Paulista,  Itaquera, Interlagos, Jardim Angela e no bairro de Pirituba.<\/p>\n<p>Para  participar, basta ligar para o banco S\u00e3o Paulo Confia no telefone (011)  2797-7300 e verificar uma vaga mais pr\u00f3xima de sua resid\u00eancia.<\/p>\n<p><em>Fonte: Prefeitura de S. Paulo<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Come\u00e7am na pr\u00f3xima segunda-feira (6\/8), as inscri\u00e7\u00f5es para novas turmas do Curso B\u00e1sico de Empreendedorismo, da Academia de Microfinan\u00e7as do banco de microcr\u00e9dito do S\u00e3o Paulo Confia, da Secretaria Municipal de Desenvolvimento Econ\u00f4mico e do Trabalho. S\u00e3o 3 mil vagas, com 12h de curso, divididas em 4 encontros de tr\u00eas horas cada. No per\u00edodo matutino, as aulas v\u00e3o das 9h ao meio-dia e no vespertino das 14h \u00e0s 17h. O curso \u00e9 gratuito e est\u00e1 aberto para todos que tiverem interesse em participar e, ao final, os participantes recebem um certificado. Durante as aulas, os participantes aprendem como controlar o <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-835","post","type-post","status-publish","format-standard","hentry","category-noticias-no-centro-sp"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Come\u00e7am na pr\u00f3xima segunda-feira (6\/8), as inscri\u00e7\u00f5es para novas turmas do Curso B\u00e1sico de Empreendedorismo, da Academia de Microfinan\u00e7as do banco de microcr\u00e9dito do S\u00e3o Paulo Confia, da Secretaria Municipal de Desenvolvimento Econ\u00f4mico e do Trabalho. S\u00e3o 3 mil vagas, com 12h de curso, divididas em 4 encontros de tr\u00eas horas cada. No per\u00edodo matutino,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Encontra Centro SP\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Encontra Centro SP | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"S\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro | Encontra Centro SP\" \/>\n\t\t<meta property=\"og:description\" content=\"Come\u00e7am na pr\u00f3xima segunda-feira (6\/8), as inscri\u00e7\u00f5es para novas turmas do Curso B\u00e1sico de Empreendedorismo, da Academia de Microfinan\u00e7as do banco de microcr\u00e9dito do S\u00e3o Paulo Confia, da Secretaria Municipal de Desenvolvimento Econ\u00f4mico e do Trabalho. S\u00e3o 3 mil vagas, com 12h de curso, divididas em 4 encontros de tr\u00eas horas cada. No per\u00edodo matutino,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-08-02T11:43:14+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-29T19:22:25+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"S\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro | Encontra Centro SP\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Come\u00e7am na pr\u00f3xima segunda-feira (6\/8), as inscri\u00e7\u00f5es para novas turmas do Curso B\u00e1sico de Empreendedorismo, da Academia de Microfinan\u00e7as do banco de microcr\u00e9dito do S\u00e3o Paulo Confia, da Secretaria Municipal de Desenvolvimento Econ\u00f4mico e do Trabalho. S\u00e3o 3 mil vagas, com 12h de curso, divididas em 4 encontros de tr\u00eas horas cada. No per\u00edodo matutino,\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\\\/#article\",\"name\":\"S\\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro | Encontra Centro SP\",\"headline\":\"S\\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\"},\"datePublished\":\"2012-08-02T09:43:14-03:00\",\"dateModified\":\"2019-04-29T16:22:25-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias Centro SP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"name\":\"Not\\u00edcias Centro SP\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias Centro SP\",\"item\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\\\/#listItem\",\"name\":\"S\\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\\\/#listItem\",\"position\":3,\"name\":\"S\\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/noticias-no-centro-sp\\\/#listItem\",\"name\":\"Not\\u00edcias Centro SP\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\",\"name\":\"Encontra Centro SP\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Centro SP e regi\\u00e3o.\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/\",\"name\":\"Encontra Centro SP\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Encontra Centro SP\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\\\/#webpage\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\\\/\",\"name\":\"S\\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro | Encontra Centro SP\",\"description\":\"Come\\u00e7am na pr\\u00f3xima segunda-feira (6\\\/8), as inscri\\u00e7\\u00f5es para novas turmas do Curso B\\u00e1sico de Empreendedorismo, da Academia de Microfinan\\u00e7as do banco de microcr\\u00e9dito do S\\u00e3o Paulo Confia, da Secretaria Municipal de Desenvolvimento Econ\\u00f4mico e do Trabalho. S\\u00e3o 3 mil vagas, com 12h de curso, divididas em 4 encontros de tr\\u00eas horas cada. No per\\u00edodo matutino,\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/author\\\/ecentrosaopaulo\\\/#author\"},\"datePublished\":\"2012-08-02T09:43:14-03:00\",\"dateModified\":\"2019-04-29T16:22:25-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/\",\"name\":\"Encontra Centro SP\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Centro SP e regi\\u00e3o.\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracentrosaopaulo.com.br\\\/sobre\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"S\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro | Encontra Centro SP","description":"Come\u00e7am na pr\u00f3xima segunda-feira (6\/8), as inscri\u00e7\u00f5es para novas turmas do Curso B\u00e1sico de Empreendedorismo, da Academia de Microfinan\u00e7as do banco de microcr\u00e9dito do S\u00e3o Paulo Confia, da Secretaria Municipal de Desenvolvimento Econ\u00f4mico e do Trabalho. S\u00e3o 3 mil vagas, com 12h de curso, divididas em 4 encontros de tr\u00eas horas cada. No per\u00edodo matutino,","canonical_url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\/#article","name":"S\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro | Encontra Centro SP","headline":"S\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro","author":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"publisher":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization"},"datePublished":"2012-08-02T09:43:14-03:00","dateModified":"2019-04-29T16:22:25-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\/#webpage"},"isPartOf":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\/#webpage"},"articleSection":"Not\u00edcias Centro SP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","name":"Not\u00edcias Centro SP"}},{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","position":2,"name":"Not\u00edcias Centro SP","item":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\/#listItem","name":"S\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\/#listItem","position":3,"name":"S\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro","previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/#listItem","name":"Not\u00edcias Centro SP"}}]},{"@type":"Organization","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization","name":"Encontra Centro SP","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/"},{"@type":"Person","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/","name":"Encontra Centro SP","image":{"@type":"ImageObject","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","width":96,"height":96,"caption":"Encontra Centro SP"}},{"@type":"WebPage","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\/#webpage","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\/","name":"S\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro | Encontra Centro SP","description":"Come\u00e7am na pr\u00f3xima segunda-feira (6\/8), as inscri\u00e7\u00f5es para novas turmas do Curso B\u00e1sico de Empreendedorismo, da Academia de Microfinan\u00e7as do banco de microcr\u00e9dito do S\u00e3o Paulo Confia, da Secretaria Municipal de Desenvolvimento Econ\u00f4mico e do Trabalho. S\u00e3o 3 mil vagas, com 12h de curso, divididas em 4 encontros de tr\u00eas horas cada. No per\u00edodo matutino,","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#website"},"breadcrumb":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\/#breadcrumblist"},"author":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"creator":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/author\/ecentrosaopaulo\/#author"},"datePublished":"2012-08-02T09:43:14-03:00","dateModified":"2019-04-29T16:22:25-03:00"},{"@type":"WebSite","@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#website","url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/","name":"Encontra Centro SP","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Encontra Centro SP | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Centro SP e regi\u00e3o.","og:type":"article","og:title":"S\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro | Encontra Centro SP","og:description":"Come\u00e7am na pr\u00f3xima segunda-feira (6\/8), as inscri\u00e7\u00f5es para novas turmas do Curso B\u00e1sico de Empreendedorismo, da Academia de Microfinan\u00e7as do banco de microcr\u00e9dito do S\u00e3o Paulo Confia, da Secretaria Municipal de Desenvolvimento Econ\u00f4mico e do Trabalho. S\u00e3o 3 mil vagas, com 12h de curso, divididas em 4 encontros de tr\u00eas horas cada. No per\u00edodo matutino,","og:url":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\/","article:published_time":"2012-08-02T11:43:14+00:00","article:modified_time":"2019-04-29T19:22:25+00:00","twitter:card":"summary","twitter:title":"S\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro | Encontra Centro SP","twitter:description":"Come\u00e7am na pr\u00f3xima segunda-feira (6\/8), as inscri\u00e7\u00f5es para novas turmas do Curso B\u00e1sico de Empreendedorismo, da Academia de Microfinan\u00e7as do banco de microcr\u00e9dito do S\u00e3o Paulo Confia, da Secretaria Municipal de Desenvolvimento Econ\u00f4mico e do Trabalho. S\u00e3o 3 mil vagas, com 12h de curso, divididas em 4 encontros de tr\u00eas horas cada. No per\u00edodo matutino,"},"aioseo_meta_data":{"post_id":"835","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-18 19:02:55","updated":"2025-11-14 11:34:29","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/\" title=\"Not\u00edcias Centro SP\">Not\u00edcias Centro SP<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tS\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre"},{"label":"Not\u00edcias Centro SP","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/noticias-no-centro-sp\/"},{"label":"S\u00e3o Paulo Confia abre novas turmas para o curso gratuito de empreendedorismo no Centro","link":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/sao-paulo-confia-abre-novas-turmas-para-o-curso-gratuito-de-empreendedorismo-no-centro\/"}],"_links":{"self":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=835"}],"version-history":[{"count":0,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/posts\/835\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontracentrosaopaulo.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}